{"id":81060,"date":"2022-05-03T14:49:33","date_gmt":"2022-05-03T17:49:33","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=81060"},"modified":"2022-05-03T14:49:33","modified_gmt":"2022-05-03T17:49:33","slug":"los-prostibulos-de-la-antigua-roma","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/ar\/blog\/los-prostibulos-de-la-antigua-roma\/","title":{"rendered":"\u0628\u064a\u0648\u062a \u0627\u0644\u062f\u0639\u0627\u0631\u0629 \u0641\u064a \u0631\u0648\u0645\u0627 \u0627\u0644\u0642\u062f\u064a\u0645\u0629"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-las-relaciones-matrimoniales-eran-entendidas-en-el-mundo-clasico-como-un-contrato-por-intereses-familiares-y-como-mecanismo-para-engendrar-hijos-legitimos-que-heredasen-la-propiedad-y-la-situacion-de-sus-padres-el-placer-sexual-se-buscaba-en-lugares-fuera-del-hogar-donde-muchas-de-las-practicas-que-se-realizaban-eran-consideradas-impudicas-para-una-matrona-romana\">Las relaciones matrimoniales eran entendidas en el mundo cl\u00e1sico como un contrato por intereses familiares y como mecanismo para engendrar hijos leg\u00edtimos que heredasen la propiedad y la situaci\u00f3n de sus padres. El placer sexual se buscaba en lugares fuera del hogar donde muchas de las pr\u00e1cticas que se realizaban eran consideradas imp\u00fadicas para una matrona romana.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<strong>Derecho romano<\/strong>&nbsp;defin\u00eda a las meretrices como \u201cpersonas que abiertamente obtienen dinero con su cuerpo\u201d pues&nbsp;<strong>la prostituci\u00f3n era considerara un bien social y necesario<\/strong>. Gracias a esto sabemos mucho sobre los&nbsp;<strong>tipos de prostitutas<\/strong>, sus actividades e incluso los precios de&nbsp;<strong>prostitutas<\/strong>&nbsp;y&nbsp;<strong>prostitutos<\/strong>, ya que tambi\u00e9n exist\u00eda la prostituci\u00f3n de hombres j\u00f3venes dedicados a un p\u00fablico femenino y homosexual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sabemos pues que<strong>\u00a0esta pr\u00e1ctica se ejerc\u00eda con normalidad\u00a0<\/strong>en calles concretas, ba\u00f1os p\u00fablicos o en diversas\u00a0<em>tabernae<\/em><a href=\"https:\/\/academiaplay.es\/prostibulos-antigua-roma\/#_ftn1\"><strong>[1]<\/strong><\/a>. No obstante, en el siguiente art\u00edculo pretendo\u00a0<strong>centrar la atenci\u00f3n en los edificios dedicados al placer, los lupanares,<\/strong>\u00a0para saber c\u00f3mo se organizaban, cu\u00e1l era el ambiente que se respiraba y c\u00f3mo encajaban en el pensamiento romano de la \u00e9poca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En el siglo IV d.C en la ciudad de Roma estaban registrados oficialmente m\u00e1s de 50 locales de prostituci\u00f3n<\/strong>. En barrios como Subura o el Trastevere exist\u00edan los locales m\u00e1s s\u00f3rdidos mientras el Aventino acog\u00eda locales con un nivel econ\u00f3mico m\u00e1s elevado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos locales eran f\u00e1cilmente identificables, primero porque<strong>&nbsp;exist\u00edan se\u00f1ales que indicaban la direcci\u00f3n hacia el prost\u00edbulo m\u00e1s cercano<\/strong>, ya sean falos grabados en el pavimento del suelo o se\u00f1ales verticales. Adem\u00e1s, estos locales ten\u00edan un&nbsp;<strong>enorme falo pintado de rojo bermell\u00f3n<\/strong>, que serv\u00eda de aldaba de la puerta. Tambi\u00e9n por la noche, los establecimientos estar\u00edan iluminados por&nbsp;<strong>faroles de aceite con formas f\u00e1licas<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exist\u00edan muchos tipos de prost\u00edbulos en el mundo romano,<\/strong>\u00a0de modo que resulta muy dif\u00edcil establecer una regla arquitect\u00f3nica general para este edificio. La excelente conservaci\u00f3n de la ciudad de\u00a0<a href=\"https:\/\/academiaplay.es\/vesubio-volcan-sepulto-pompeya\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Pompeya<\/strong>\u00a0<\/a>ha aportado datos al respecto, con unos 30 edificios relacionados con la prostituci\u00f3n. Entre ellos, el\u00a0<em>Lupanare\u00a0<\/em>es el burdel m\u00e1s conocido y mejor estudiado, del que podemos conocer un ejemplo de c\u00f3mo era la estructura de estos locales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El&nbsp;<em>Lupanare<\/em>&nbsp;contaba con&nbsp;<strong>dos plantas<\/strong>, una a nivel del suelo y un primer piso.<br \/>La planta baja estaba destinada al acceso de esclavos o de las clases m\u00e1s pobres, mientras que la superior estaba dedicada a una clientela de mayor poder adquisitivo. En esta planta se<strong>&nbsp;dispon\u00eda tambi\u00e9n de un buen balc\u00f3n desde el cual las prostitutas seduc\u00edan a los peatones con sus propuestas y movimientos sensuales<\/strong>.<\/p>\n\n\n\n<div id=\"attachment_24453\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/academiaplay.es\/wp-content\/uploads\/2018\/09\/web-prost%C3%ADbulos-2.jpg\" alt=\"\" class=\"wp-image-24453\"\/><figcaption>Invocaci\u00f3n de Pr\u00edapo. Grabado del siglo XIX de un supuesto bajorrelieve de Pompeya.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En el vest\u00edbulo de estos locales se situaba un&nbsp;<strong>Pr\u00edapo<\/strong><a href=\"https:\/\/academiaplay.es\/prostibulos-antigua-roma\/#_ftn2\">[2]<\/a>&nbsp;erecto de grandes proporciones que daba la bienvenida al visitante como&nbsp;<strong>s\u00edmbolo de poder sexual masculino<\/strong>. En su interior ten\u00eda un corredor y habitaciones con cama. Se conoce que&nbsp;<strong>en la planta baja hab\u00eda normalmente un m\u00e1ximo de cinco habitaciones con una prostituta para cada una<\/strong>. Estos cub\u00edculos se denominaban \u201c<em>fornices<\/em>\u201d, nombre del que nace nuestro verbo fornicar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al piso superior se acced\u00eda por una entrada independiente que daba a una escalera y despu\u00e9s al balc\u00f3n. A este balc\u00f3n daban las diferentes habitaciones, m\u00e1s grandes y decoradas que las de la planta baja.\u00a0<strong>Este piso superior era reservado a una clientela m\u00e1s acomodada<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s adelante, en la entrada de cada uno de los&nbsp;<em>fornices<\/em>,&nbsp;<strong>hab\u00eda pinturas mostrando las especialidades sexuales de sus prostitutas y una pizarra con su nombre y sus tarifas<\/strong>, as\u00ed el cliente sab\u00eda muy bien qu\u00e9 compraba. No era lo mismo una&nbsp;<strong>cuadrantaria<\/strong>&nbsp;(denominada as\u00ed para cobrar un cuadrante por sus servicios, una miseria), que una&nbsp;<strong>felatriz<\/strong>, especialista en la felaci\u00f3n y sexo oral, una pr\u00e1ctica que ninguna mujer u hombre digno realizar\u00eda en situaci\u00f3n normal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n hab\u00eda en las entradas de los&nbsp;<em>fornices<\/em>&nbsp;carteles con la palabra&nbsp;<em>occupata<\/em>, para colgarlo en la puerta&nbsp;<strong>cuando la meretriz estaba con un cliente<\/strong>. Muchas de las paredes estaban cubiertas de pinturas que expresaban diferentes posiciones er\u00f3ticas como decoraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, las camas de los&nbsp;<em>fornices<\/em>&nbsp;eran de mortero.&nbsp;<strong>Encima se colocaba un colch\u00f3n de paja o plum\u00f3n para que el acto sexual fuera m\u00e1s c\u00f3modo<\/strong>. El \u00fanico mobiliario que conten\u00edan era una l\u00e1mpara de aceite y una palangana para limpiarse.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed pues,&nbsp;<strong>los lupanares romanos eran edificios dedicados al placer sexual normalmente masculino<\/strong>. Su perfil arquitect\u00f3nico es el resultado de la estructura ideol\u00f3gica de la sociedad romana y de la actividad que en \u00e9l se realizaba.<\/p>\n\n\n\n<div id=\"attachment_24456\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/academiaplay.es\/wp-content\/uploads\/2018\/09\/web-prost%C3%ADbulos-4.jpg\" alt=\"\" class=\"wp-image-24456\"\/><figcaption>Detalle de un fresco de Pompeya que muestra una escena sexual.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Para empezar,&nbsp;<strong>el edificio se situaba normalmente en un cruce de calles<\/strong>. Este era un punto de continua afluencia de peatones y donde eran visibles las meretrices que se paseaban por los alrededores desde cualquier calle que lo atraviesa. Este deb\u00eda ser un factor principal para atraer clientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La exhibici\u00f3n de la oferta del local continuaba en el balc\u00f3n<\/strong>. El hecho de situar las prostitutas a bailar y llamar halagos a los peatones desde un balc\u00f3n, es decir, desde un escenario elevado, implicaba una mayor visualidad de las chicas. Estas eran visibles m\u00e1s f\u00e1cilmente por los presuntos clientes, y a su vez, ellas pod\u00edan controlar mejor lo que pasaba en las calles circundantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tanta publicidad contrasta el punto de privacidad que busca el cliente para el acto sexual con la divisi\u00f3n del espacio en peque\u00f1as habitaciones<\/strong>. Es cierto que cada cub\u00edculo pod\u00eda estar dedicado a una pr\u00e1ctica sexual diferente, pero el espacio reducido y la posibilidad de tener una puerta o tela para tapar la entrada denotan esta voluntad. Adem\u00e1s, el hecho de que el espacio fuera reducido y el mobiliario escaso implicaba tambi\u00e9n una precauci\u00f3n frente las posibles agresiones a prostitutas. Reduciendo el espacio y los objetos que podr\u00edan utilizarse como arma se evitar\u00edan agresiones y la fuga del posible agresor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Se diferencian tambi\u00e9n dos niveles, la planta baja para los pobres y el primer piso para los ricos<\/strong>. El acceso en estos espacios era independiente, de forma que los dos tipos de clientes no coincid\u00edan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, cada una de las habitaciones del primer piso daba directamente al balc\u00f3n.<strong>&nbsp;\u00bfPor qu\u00e9 tener esta comunicaci\u00f3n entre balc\u00f3n y habitaci\u00f3n?<\/strong>&nbsp;En mi opini\u00f3n esto se deber\u00eda a la posibilidad de los clientes ricos de elegir prostituta. Los peatones adinerados, a los cuales atra\u00edan las diferentes meretrices, podr\u00edan elegir a \u201cla que m\u00e1s les gustaba\u201d, a modo de escaparate.<strong>&nbsp;Si cliente y prostituta acordaban un acto sexual, esta necesitar\u00eda un acceso directo a su habitaci\u00f3n para encontrarse con \u00e9l<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, hay que hablar de la&nbsp;<strong>decoraci\u00f3n<\/strong>. Junto con el&nbsp;<strong>Pr\u00edapo<\/strong>, las pinturas murales de las paredes tambi\u00e9n tendr\u00edan una funci\u00f3n muy clara:&nbsp;<strong>excitar al visitante<\/strong>. Las escenas sexuales, por una parte, mostraban lo que se podr\u00eda practicar en aquel lupanar, y por la otra excitaba e incitaba a los visitantes a&nbsp;<strong>realizar y descubrir nuevas posturas y pr\u00e1cticas sexuales<\/strong>.<\/p>\n\n\n\n<div id=\"attachment_24454\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/academiaplay.es\/wp-content\/uploads\/2018\/09\/web-prost%C3%ADbulos-3.jpg\" alt=\"\" class=\"wp-image-24454\"\/><figcaption>Fresco de Pr\u00edapo en la casa de los Vettii, Pompeya. Pr\u00edapo est\u00e1 pesando su miembro en una balanza contra la ganancia obtenida de los campos.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed pues,&nbsp;<strong>los burdeles de Roma se han descrito como lugares sucios<\/strong>, de escasa ventilaci\u00f3n, llenos de malos olores y caracterizados por la falta de higiene y la acumulaci\u00f3n de holl\u00edn y gases de las numerosas l\u00e1mparas.&nbsp;<strong>Aunque tambi\u00e9n, estaban los locales m\u00e1s lujosos<\/strong>, perfectamente preparados y con todo lujo de detalles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el tipo de barrio donde te adentrases pod\u00edas correr peligro, por lo que los personajes m\u00e1s ricos, ir\u00edan acompa\u00f1ados de su propia escolta de esclavos armados con faroles y palos. Como bien nos dice\u00a0<strong>Plauto<\/strong>\u00a0\u201cAqu\u00ed tenemos todas las categor\u00edas de hombres: caballeros, de a pie, emancipado, ladr\u00f3n, esclavo fugado, presidario huido, y esclavos por deudas.\u00a0<strong>Las suripantas reciben a cualquiera con tal de que tenga dinero<\/strong>\u201c.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte,<strong>&nbsp;las prostitutas<\/strong>&nbsp;<strong>o&nbsp;<em>lupae<\/em><\/strong><a href=\"https:\/\/academiaplay.es\/prostibulos-antigua-roma\/#_ftn3\"><strong>[3]<\/strong><\/a>&nbsp;<strong>se exhibir\u00edan en la calle<\/strong>, paseando por la acera captando clientes, solas, en pareja o formando corrillos. Tambi\u00e9n las habr\u00eda que te reclamaban desde los balcones del lupanar o desde su misma puerta, tal y como hemos visto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La zona de recepci\u00f3n, mejor o peor preparada seg\u00fan el nivel del prost\u00edbulo, pod\u00eda incluir servicios de comida y bebida, tal y como nos lo describe Plauto<\/strong>&nbsp;\u201clleno de rincones oscuros y cuartuchos. Se bebe y se come como en las tabernas. Alineados en anaqueles a lo largo de las paredes hay c\u00e1ntaros sellados con pez, de largas etiquetas, indicio de que es lugar frecuentado por buenos bebedores\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En esta zona las prostitutas se mostraban a los clientes vestidas con gasas o desnudas<\/strong>, anunci\u00e1ndose seg\u00fan su especialidad, la mayor\u00eda con nombres ex\u00f3ticos y seguramente mintiendo sobre su lugar de procedencia, atribuy\u00e9ndose un origen en alg\u00fan punto ex\u00f3tico y lejano del&nbsp;<a href=\"https:\/\/academiaplay.es\/el-imperio-romano-10-minutos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Imperio Romano<\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No querr\u00eda cerrar este apartado sin mencionar una&nbsp;<strong>fuente de informaci\u00f3n primordial<\/strong>&nbsp;para conocer de primera mano el pensamiento de aquellas gentes:&nbsp;<strong>los&nbsp;<em>grafitis<\/em>&nbsp;que clientes y prostitutas dejaron en las paredes de estas casas<\/strong>. En Pompeya se han documentado m\u00e1s de 120 inscripciones, las cuales recuerdan mucho a las que se dejan hoy en d\u00eda a cualquier ba\u00f1o p\u00fablico:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs\u00ed que llegu\u00e9 aqu\u00ed, foll\u00e9 y regres\u00e9 a casa\u201d (CIL, IV, 2346)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cFesto jodi\u00f3 aqu\u00ed con sus camaradas\u201d (CIL, IV, 3935)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHaspocras foll\u00f3 aqu\u00ed muy a gusto con Drauca por un denario\u201d (CIL, IV, 2193)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cQuien esto escribe est\u00e1 enamorado; quien lo lee, toma por el culo; el que escucha, se pone caliente; quien pasa de largo, es un maric\u00f3n; que los osos se me zampen a m\u00ed, y yo, que lo leo, un cipote\u201d (CIL, IV, 2360)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCayo Valerio Venusto, soldado de la primera cohorte pretoriana, follador m\u00e1ximo\u201d (CIL, IV, 2145)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCrisero y Suceso jodimos aqu\u00ed tres veces cada uno\u201d (CIL, 4816)<\/p>\n\n\n\n<div id=\"attachment_24460\" class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/academiaplay.es\/wp-content\/uploads\/2018\/09\/web-prost%C3%ADbulos-5.jpg\" alt=\"\" class=\"wp-image-24460\"\/><figcaption>Detalle de un fresco de Pompeya que muestra una escena sexual.<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En resumen,&nbsp;<strong>vemos c\u00f3mo los lupanares eran lugares de referencia para el placer, normalmente masculino<\/strong>. La pol\u00edtica romana entendi\u00f3 la necesidad social de la existencia de este oficio por lo que legislaba y regulaba todos los locales y trabajadores relacionados con la prostituci\u00f3n. Tal y como escribi\u00f3 el historiador romano&nbsp;<strong>T\u00e1cito<\/strong>,&nbsp;<strong>las mujeres que quer\u00edan ejercer la prostituci\u00f3n ten\u00edan que registrarse en la oficina del edil<\/strong>&nbsp;para disponer de la&nbsp;<em>licentia stupri&nbsp;<\/em>y as\u00ed prostituirse legalmente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De este modo&nbsp;<strong>la civilizaci\u00f3n romana entend\u00eda la prostituci\u00f3n como algo normal y cotidiano<\/strong>. El sexo por placer, el sexo social, estaba reglado y permitido, incluso difundido y aceptado como una necesidad en el seno de la comunidad. La sociedad romana toleraba unas conductas y \u00e9ticas bastante promiscuas y liberales, donde las relaciones extramatrimoniales eran totalmente normales. La \u00fanica exigencia era mantenerse dentro de los l\u00edmites de la normativa legal y social.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hay que entender que las relaciones maritales, amorosas y sexuales en la antig\u00fcedad cl\u00e1sica ten\u00edan un sentido muy diferente al que entendemos hoy d\u00eda<\/strong>. Las bodas representaban contratos entre&nbsp;<a href=\"https:\/\/academiaplay.es\/familia-romana\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>familias<\/strong>&nbsp;<\/a>y un sistema por el que engendrar hijos que siguieran el linaje. La diversi\u00f3n y el placer se buscaban en lugares especializados restando la casa para los quehaceres y los negocios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe observar tambi\u00e9n c\u00f3mo&nbsp;<strong>la prostituci\u00f3n era accesible a todas las capas sociales<\/strong>. Exist\u00edan diferencias de lujos, precios y prostitutas seg\u00fan el nivel adquisitivo de los clientes, es decir, encontramos una&nbsp;<strong>estratificaci\u00f3n del placer sexual<\/strong>&nbsp;donde el negocio ampl\u00eda su p\u00fablico, pero jerarquiza los servicios prestados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, apuntar a la&nbsp;<strong>influencia griega de la b\u00fasqueda primordial del placer,<\/strong>&nbsp;aunque seguramente por herencia del hedonismo racional de&nbsp;<strong>Epicuro<\/strong>, los romanos tambi\u00e9n entend\u00edan que&nbsp;<strong>todo tiene su justa medida<\/strong>, incluso para las visitas a prostitutas. Un claro ejemplo de esta moralidad la encontramos en una an\u00e9cdota de&nbsp;<strong>Cat\u00f3n el Viejo<\/strong>&nbsp;que vio salir al hijo de un amigo suyo de un prost\u00edbulo, \u00e9ste avergonzado retir\u00f3 la mirada, aunque Cat\u00f3n le dijo \u201clo que haces est\u00e1 bien, as\u00ed cuando el deseo te hinche las venas no abusar\u00e1s de las mujeres decentes\u201d. Pero al d\u00eda siguiente volvi\u00f3 a cruzarse con el joven que sal\u00eda otra vez del prost\u00edbulo y esta vez le recrimin\u00f3 dici\u00e9ndole \u201cMuchacho, te dije que estaba bien que visitaras ese lugar, no que vivieras en \u00e9l\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bibliograf\u00eda y Webgraf\u00eda<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAlkmst\u201d (2014). La prostituci\u00f3n en la cultura romana. [<a href=\"http:\/\/historsex.blogspot.com\/2014\/05\/la-prostitucion-en-la-cultura-romana.html\" target=\"_blank\" rel=\"noreferrer noopener\">online<\/a>] Historsex.blogspot.com [Consultado el 2 Sep. 2018].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dom\u00e9nech, Asunci\u00f3n (2012) \u2013 La Aventura de la Historia \u2013 164 \u2013 Roma, el negocio de la prostituci\u00f3n. Editorial: Unidad Editorial Sociedad de Revistas S. L. U.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00fcbbes, F. (1979). Arch\u00e4elogisches F\u00fchrer Pompeji. p.302.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">McClure, L. (2002).&nbsp;<em>Sexuality and gender in the classical world<\/em>. Oxford, UK: Blackwell Publishers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">McGinn, T. (2007).&nbsp;<em>Prostitution, sexuality, and the law in ancient Rome<\/em>. Oxford: Oxford Univ. Press.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sanz, J. (2011). Clases de putas en la antigua Roma. [<a href=\"http:\/\/historiasdelahistoria.com\/2011\/06\/14\/clases-de-putas-en-la-antigua-roma\" target=\"_blank\" rel=\"noreferrer noopener\">online<\/a>] Historias de la Historia [Consultado el 1 Sep. 2018].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sanz, J. and Priego, J. (2016). PROSTITUCI\u00d3N, FEMENINA Y MASCULINA, EN LA ANTIGUA ROMA | Historias de la Historia. [<a href=\"https:\/\/www.youtube.com\/watch?v=DfDe6PjoWZI\" target=\"_blank\" rel=\"noreferrer noopener\">online<\/a>] YouTube [Consultado el 2 Sep. 2018].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vanoyeke, V. (1990).&nbsp;<em>La Prostitution en Gr\u00e8ce et \u00e0 Rome<\/em>. Paris: Les Belles Lettres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Williams, C. (2010).&nbsp;<em>Roman homosexuality<\/em>. New York: Oxford University Press.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/academiaplay.es\/prostibulos-antigua-roma\/#_ftnref1\">[1]<\/a>&nbsp;Las&nbsp;<em>tabernae&nbsp;<\/em>eran tiendas situadas en los bajos de los edificios o las&nbsp;<em>domi&nbsp;<\/em>(casas). Tambi\u00e9n se conoc\u00eda como tabernas a las posadas situadas en las principales calzadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/academiaplay.es\/prostibulos-antigua-roma\/#_ftnref2\">[2]<\/a>&nbsp;En la mitolog\u00eda griega, Pr\u00edapo es un dios menor r\u00fastico de la fertilidad, tanto de la vegetaci\u00f3n como de todos los animales relacionados con la vida agr\u00edcola, y un personaje puramente f\u00e1lico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/academiaplay.es\/prostibulos-antigua-roma\/#_ftnref3\">[3]<\/a>&nbsp;La&nbsp;<em>lupa&nbsp;<\/em>o en plural&nbsp;<em>lupae&nbsp;<\/em>era la denominaci\u00f3n que recib\u00edan las prostitutas que ejerc\u00edan \u00fanica y exclusivamente en los lupanares.<\/p>\n","protected":false},"featured_media":81061,"template":"","blog-categoria":[43],"class_list":["post-81060","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-historia-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historia de los Prost\u00edbulos de la Antigua Roma<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia de los Prost\u00edbulos de la Antigua Roma\" \/>\n<meta property=\"og:description\" content=\"Las relaciones matrimoniales eran entendidas en el mundo cl\u00e1sico como un contrato por intereses familiares y como mecanismo para engendrar hijos leg\u00edtimos que heredasen la propiedad y la situaci\u00f3n de sus padres. El placer sexual se buscaba en lugares fuera del hogar donde muchas de las pr\u00e1cticas que se realizaban eran consideradas imp\u00fadicas para una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/ar\/blog\/los-prostibulos-de-la-antigua-roma\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/\",\"name\":\"Historia de los Prost\u00edbulos de la Antigua Roma\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-05-03T17:49:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/los-prostibulos-de-la-antigua-roma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los Prost\u00edbulos de la Antigua Roma\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062a\u0627\u0631\u064a\u062e \u0628\u064a\u0648\u062a \u0627\u0644\u062f\u0639\u0627\u0631\u0629 \u0627\u0644\u0631\u0648\u0645\u0627\u0646\u064a\u0629 \u0627\u0644\u0642\u062f\u064a\u0645\u0629","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ar_AR","og_type":"article","og_title":"Historia de los Prost\u00edbulos de la Antigua Roma","og_description":"Las relaciones matrimoniales eran entendidas en el mundo cl\u00e1sico como un contrato por intereses familiares y como mecanismo para engendrar hijos leg\u00edtimos que heredasen la propiedad y la situaci\u00f3n de sus padres. El placer sexual se buscaba en lugares fuera del hogar donde muchas de las pr\u00e1cticas que se realizaban eran consideradas imp\u00fadicas para una [&hellip;]","og_url":"https:\/\/blog.argxp.com\/ar\/blog\/los-prostibulos-de-la-antigua-roma\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"12 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/","url":"https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/","name":"\u062a\u0627\u0631\u064a\u062e \u0628\u064a\u0648\u062a \u0627\u0644\u062f\u0639\u0627\u0631\u0629 \u0627\u0644\u0631\u0648\u0645\u0627\u0646\u064a\u0629 \u0627\u0644\u0642\u062f\u064a\u0645\u0629","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-05-03T17:49:33+00:00","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/it\/blog\/los-prostibulos-de-la-antigua-roma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"Los Prost\u00edbulos de la Antigua Roma"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"\u0627\u0644\u0645\u062f\u0648\u0646\u0629","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/ar\/wp-json\/wp\/v2\/blog\/81060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/ar\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/ar\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/ar\/wp-json\/wp\/v2\/media?parent=81060"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/ar\/wp-json\/wp\/v2\/blog-categoria?post=81060"}],"curies":[{"name":"\u0644\u0639\u0628 \u062c\u064a\u062f","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}