{"id":50598,"date":"2021-02-26T17:37:52","date_gmt":"2021-02-26T20:37:52","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=50598"},"modified":"2021-02-26T17:37:52","modified_gmt":"2021-02-26T20:37:52","slug":"bella-y-sola-julieta-la-acompanante-milagrosa-pt-2","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/es_es\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/","title":{"rendered":"Bella y sola: Julieta, la acompa\u00f1ante milagrosa &#8211; Pt. 2"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\" id=\"h-en-la-primera-parte-julieta-se-desnud-completamente-ebria-en-la-escalera-y-los-vecinos-se-encontraban-a-punto-de-atraparla-infraganti-y-completamente-expuesta-a-mi-se-me-par-no-solo-el-coraz-n\">En la primera parte Julieta se desnud\u00f3 completamente ebria en la escalera y los vecinos se encontraban a punto de atraparla infraganti y completamente expuesta; a mi se me par\u00f3 no solo el coraz\u00f3n&#8230;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Me asom\u00e9 con Julieta con una curiosidad algo terror\u00edfica y solo uno de los hombres hab\u00eda puesto atenci\u00f3n a nuestra presencia, qued\u00f3 paralizado, intent\u00f3 hacer caso omiso a lo que ve\u00eda para no alertar a su pr\u00f3jimo. De todos modos se empez\u00f3 a enfurecer y comenz\u00f3 a caminar m\u00e1s r\u00e1pido, nerviosamente. Los dem\u00e1s charlaban y jugaban muy a gusto, o\u00eda como el otro se\u00f1or inadvertido que hablaba con la se\u00f1ora expresaba: -All\u00ed donde queman libros, acaban por quemar tambi\u00e9n a seres humanos, como bien dijo el gigante de Hendel- mientras la mujer asent\u00eda con sumo inter\u00e9s y se aproximaban a la puerta de salida. Los m\u00e1s peque\u00f1os correteaban por delante y el que estaba enterado del esc\u00e1ndalo se apresur\u00f3 a abrir. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El v\u00e9rtigo nos consum\u00eda a los tres, tanto que padre de familia que nos hab\u00eda advertido, en <strong>Julieta que se estaba exhibiendo totalmente ante sus vecinos<\/strong>, que quiz\u00e1 ver\u00eda cada ma\u00f1ana, ahora <strong>con su culo al aire y <em>tetas <\/em>danzando<\/strong>;&nbsp;y yo, que parec\u00eda responsable vaya a saber de que perversidad.&nbsp;Pero los mir\u00e9 y en m\u00ed mente brot\u00f3 una repentina respuesta, al hombre que comentaba despreocupado pero solemne, aquella frase antes mencionada. Pens\u00e9, fue Heine y no Hendel, quien la hab\u00eda dicho la frase. Largu\u00e9 una carcajada explosiva, no hab\u00eda manera de seguir ocultando el \u00e9xtasis a causa de todo lo que all\u00ed ocurr\u00eda y lo que me ven\u00eda ocurriendo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estall\u00e9 naturalmente a causa del <em>ardiente y loco c\u00f3ctel de sensaciones<\/em> que se iban sumando vertiginosamente hac\u00eda&nbsp;ya varios minutos. Mi s\u00e1tira risa alert\u00f3 a todos de nuestra presencia, no pod\u00eda creer que un pensamiento as\u00ed me asaltara en ese momento, todos se dieron vuelta hacia nosotros menos el hombre que si ya se hab\u00eda recatado de que <strong>su joven vecina sub\u00eda la escalera completamente <em>desnuda<\/em><\/strong>. Cuando mir\u00e9 a Julieta ya se hab\u00eda escabullido, huyendo como un fantasma, o un preso, con sus nalgas veloces. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No pod\u00eda dejar de re\u00edrme como un loco, y me apure a perseguirla. Todos quedaron sumamente afectados, <strong>mostr\u00f3 sus encantos ante todos por unos instantes<\/strong>. Nos ocultamos en el pasillo del primer piso donde si no hab\u00eda ninguna luz (hasta ahora). Y Julieta se acomod\u00f3 en un costado en plena oscuridad a sufrir por su golpe, ahora que pod\u00eda hacerlo&nbsp;con mayor libertad. Deb\u00eda calmar mi euforia nerviosa, me correspond\u00eda ver que tanto se hab\u00eda lastimado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me enternec\u00ed hasta la pompa y no pod\u00eda creer que una dama <strong>tan bella y <em>desnuda <\/em>en la oscuridad<\/strong> tuviese que sufrir ese dolor. Ya no quer\u00eda que sufriera ning\u00fan dolor del mundo, quer\u00eda darle cobija, y protegerla, y porque no privarla de la conducta loca que ven\u00eda manifestando. Quer\u00eda hacerla feliz, darle lo que mejor fuese para ella, deb\u00eda ayudarla. La ternura puede trastornarlo a uno a veces, no se si lo saben,&nbsp;o al menos a m\u00ed. \u00a1Siempre ha sido mi tal\u00f3n de Aquiles! Pero no quer\u00eda avergonzarla \u00a1basta de paternalismos! pens\u00e9, no pod\u00eda permit\u00edrmelo, no sab\u00eda ni quien era. Pero, \u00bfy si ella me amaba? \u00bfEra siquiera eso posible?.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfNo lo ven? Ya hab\u00eda ca\u00eddo en el pantano de la estupidez, y no me ayudar\u00eda a escapar ni el diablo de aquel pantano, as\u00ed sol\u00eda ocurrirme.&nbsp;Se escuch\u00f3 otro movimiento de cerradura, pero solo pareci\u00f3 sonar la puerta del vecino m\u00e1s pr\u00f3ximo que tan s\u00f3lo aseguraba la puerta y agregaba alguna traba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Me acerqu\u00e9 a la preciosa Julieta y me agach\u00e9, acaricie su cabello y trat\u00e9 de inspeccionar sus piernas, ella gem\u00eda del dolor, que era pasajero y pronto se aliviar\u00eda, pero que hab\u00eda dejado su marca.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando calm\u00f3 un poco el dolor, unos momentos m\u00e1s tarde, me mir\u00f3 con cara triple: mezcla de complicidad, terror y triunfo. Comenz\u00f3 a re\u00edrse, me pidi\u00f3 la tanga y me pregunt\u00f3 que&nbsp;qu\u00e9 hab\u00eda pasado con su ropa. -\u00a1\u00bfQu\u00e9 \u201cque pas\u00f3\u201d?!- esclam\u00e9 sin levantar mucho la voz, -\u00a1la tiraste a la plata baja!- y me re\u00ed con suma admiraci\u00f3n, la muchacha me fascinaba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Ya se eso- me contest\u00f3 -pero nadie la not\u00f3 caer? \u00bfNadie se asombro de verla tirada? \u00bfNadie la agarr\u00f3? \u00bfC\u00f3mo puede ser?-<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hac\u00eda excelentes preguntas, aunque el lugar era amplio y su ropa podr\u00eda haber ca\u00eddo en cualquier lado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Es extra\u00f1o- coment\u00e9 -\u00bfPero donde viv\u00eds? \u00a1No nos vamos a quedar ac\u00e1!-<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Podr\u00edamos- contest\u00f3, y se agach\u00f3 en la misma posici\u00f3n que la m\u00eda, largando un peque\u00f1o grito por su pierna. Su cuerpo en esa posici\u00f3n se iba haciendo mas claro, <strong>su <em>sensual silueta<\/em> herida en la oscuridad iba tomando forma<\/strong>. Mis ojos nuevamente se acostumbraban a oscuras, <strong>comenc\u00e9 a contemplar sus contornos de sus curvas<\/strong>, <strong>expuesta en su propio edificio<\/strong>, <strong>a merced de ser vista en cualquier momento por mas gente<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero no le importaba, \u00bfse trataba de m\u00ed? Me abraz\u00f3, pero luego de unos momentos me empuj\u00f3 con una maldad inocente y ca\u00ed hacia atr\u00e1s, \u00a1eso doli\u00f3, no tengo su edad!, y se sent\u00f3 arriba m\u00edo. Yo estaba completamente vestido y ella como vino al mundo, aquel contraste no solo me excitaba a mi, not\u00e9 como la dejaba ardiente a ella, <strong>sus flujos corrian<\/strong>. Arriba m\u00edo <strong>comenz\u00f3 a frotarse con mi bulto; mi pene que se hab\u00eda vuelto a erectar<\/strong> hac\u00eda ya unos momentos. <strong>Peg\u00f3 a mi sus pechos y comenz\u00f3 a besarme el cuello, frot\u00e1ndose cada vez con m\u00e1s vehemencia<\/strong>. Pronto ces\u00f3 y me bes\u00f3 tiernamente, como deshaci\u00e9ndose sobre m\u00ed, rendida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuevamente se oy\u00f3 una puerta y en un instante ya estaba buscando su puerta e intentando abrirla. Sal\u00eda un se\u00f1or de aproximadamente 60 a\u00f1os, apestado de vino y de hedor.&nbsp;Tanteaba la pared para prender alguna luz. Yo no pod\u00eda creerlo, de repente todas las luces parec\u00edan funcionar, me par\u00e9 y segu\u00ed a Julieta. La luz en efecto tambi\u00e9n funcionaba y se prendi\u00f3. Este hombre si <strong>vio esta vez en toda su plenitud la desnudez de su vecina con una expresi\u00f3n de lujuria<\/strong> casi aberrante; sorprendido, si, pero amortiguada la sorpresa por el sopor del vino y sus a\u00f1os de ebriedad. Apenas pod\u00eda hablar y solt\u00f3 un \u201c\u00bfQue haces as\u00ed desnuda princesa?\u201d. Y nos metimos ya en el departamento de Julieta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-No puedo creer que Rub\u00e9n me haya visto as\u00ed, \u00a1nonono! Que tonta que soy, \u00a1dios m\u00edo!- Exclam\u00f3. Ya no le causaba ninguna gracia su atrevimiento. Hablaba como si no supiera lo que estaba haciendo. Apresuradamente me pregunt\u00f3, -\u00a1\u00bfy la tanga?! \u00bfD\u00f3nde qued\u00f3 la tanga?-&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-\u00a1Pero si te la di a vos!- Respond\u00ed, ya con una confianza de como toda la vida.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se acerc\u00f3 de nuevo a la puerta de entrada y comenz\u00f3 a abrirla lentamente. -No, \u00a1qu\u00e9 haces!- expres\u00e9 y comenc\u00e9 a re\u00edrme, no pod\u00eda creer el desquicio de la chica que acababa de conocer. Ella miraba suspicazmente, <strong>abr\u00eda la puerta&nbsp;cada de vez en vez como para ir viendo mejor<\/strong>. Se escuch\u00f3 de lejos de nuevo al vecino hablando y cerr\u00f3 r\u00e1pido la puerta con terror. -\u00a1<strong>Se qued\u00f3 con mi tanga!<\/strong> \u00a1la puta madre! Soy una tarada!- Exclam\u00f3 -\u00a1perdon\u00e1me! No lo puedo creer- Yo no sab\u00eda qu\u00e9 decir.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong>Perd\u00ed tu tanguita<\/strong>;&nbsp;me odias, hago todo mal- Dijo frustrada y comenzando a sollozar. -\u00a1no, pero que decis, no pasa nada!- dije, y otra vez la ternura me dej\u00f3 tonto. La abrac\u00e9, ella estaba tan decepcionada de s\u00ed misma que ni me abraz\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">-Adem\u00e1s era tuya mi vida, \u00a1no m\u00eda!, tuya, no ten\u00e9s porque ponerte mal por eso- Acariciaba su cabeza, y decid\u00ed, al fin darle un beso. Devolverle el bell\u00edsimo beso que me dio a oscuras en el piso antes de ser interrumpidos. Pero se alej\u00f3 con algo de apuro, -\u00a1la tanguita era tuya, no m\u00eda! Es la que me enviaste- dijo, con algo de enojo o de cansancio, quiz\u00e1 ambas. Yo qued\u00e9 confundidisimo, pero ya comenz\u00f3 a hacerse m\u00e1s claro el l\u00edo en el que estaba metiendo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No entend\u00eda nada de lo que pasaba hac\u00eda ya rato, y no sab\u00eda ni como empezar a aclarar el asunto.&nbsp;Por supuesto, no voy a mentir, estaba <strong>completamente tentado por la sensual muchacha<\/strong>. Sin embargo algo m\u00e1s me imped\u00eda preguntar que diablos suced\u00eda y quien era ella;&nbsp;hab\u00eda algo maravilloso en ser arrastrado tan velozmente por la empinada de secuencias fogosas&nbsp;a las que Julieta me empujaba <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ella parec\u00eda que iba a continuar hablando sobre la tanga que hab\u00eda perdido, pero Interrumpi\u00f3 sus ideas por el dolor de la pierna a causa golpe que se hab\u00eda dado.&nbsp;La ayude a sentarse en un sill\u00f3n que se encontraba pr\u00f3ximo. Me propuse con suma firmeza a aclarar el asunto. No pod\u00eda continuar con la farsa ya m\u00e1s tiempo, no ser\u00eda justo para ella;&nbsp;no importaba cuanto me gustase \u00a1y ya bastante lejos hab\u00eda llevado toda la cuesti\u00f3n!,&nbsp;a pesar de haber sido yo, en cierto sentido, arrastrado por el br\u00edo de Julieta. Pero ya no hab\u00eda justificaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pronunci\u00e9 las palabras me dije: -Necesito decirte algo, esto fue rar\u00edsimo y no se por donde empezar&#8230;- Ella comenz\u00f3 a besarme ya no tiernamente, sino apasionada. No me permiti\u00f3 seguir hablando. La alej\u00e9 de mi y me propuse a continuar. Se lanz\u00f3 encima m\u00edo con fuerza, acribillando sin querer su rodilla sana justo abajo de mi ombligo. Me doli\u00f3 bastante y <strong>puso sus tetas en mi boca agarr\u00e1ndose de mi hombro<\/strong>, mientras me desabrochaba la bragueta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y&nbsp;aunque lo hac\u00eda con bastante habilidad no logr\u00f3 consumar abrirme el cierre por la posici\u00f3n en la que se encontraba, mientras me mord\u00eda tambi\u00e9n la oreja. Ced\u00ed, <strong>comenc\u00e9 a lamer sus tetas con suma golosidad<\/strong>, pronto se alejaron de mi y se puso en otra posici\u00f3n, se dispuso a lograr abrirme el cierre y sacarme el pantal\u00f3n. Lo hac\u00eda con dedicaci\u00f3n, como si no quisiese arruinarme la ropa. Yo me encontraba completamente rendido, quit\u00f3 mi saco, desabroch\u00f3 mi camisa y la ayude a quit\u00e1rmela.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1Descubre las mejores <strong><a href=\"https:\/\/argentinaxp.com\/profesion\/escorts\/\" target=\"_blank\" rel=\"noreferrer noopener\">Escorts<\/a> VIP<\/strong> en Argentina XP!<\/p>\n","protected":false},"featured_media":50613,"template":"","blog-categoria":[44],"class_list":["post-50598","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-relatos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bella y sola: Julieta, la acompa\u00f1ante milagrosa Parte 2<\/title>\n<meta name=\"description\" content=\"Julieta se desnud\u00f3 completamente mientras sub\u00eda la escalera y los vecinos la atrapan infraganti con el culo al aire. Ella escapa.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bella y sola: Julieta, la acompa\u00f1ante milagrosa Parte 2\" \/>\n<meta property=\"og:description\" content=\"Julieta se desnud\u00f3 completamente mientras sub\u00eda la escalera y los vecinos la atrapan infraganti con el culo al aire. Ella escapa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/es_es\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/\",\"name\":\"Bella y sola: Julieta, la acompa\u00f1ante milagrosa Parte 2\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-02-26T20:37:52+00:00\",\"description\":\"Julieta se desnud\u00f3 completamente mientras sub\u00eda la escalera y los vecinos la atrapan infraganti con el culo al aire. Ella escapa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bella y sola: Julieta, la acompa\u00f1ante milagrosa &#8211; Pt. 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bella y sola: Julieta, la acompa\u00f1ante milagrosa Parte 2","description":"Julieta se desnud\u00f3 completamente mientras sub\u00eda la escalera y los vecinos la atrapan infraganti con el culo al aire. Ella escapa.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"es_ES","og_type":"article","og_title":"Bella y sola: Julieta, la acompa\u00f1ante milagrosa Parte 2","og_description":"Julieta se desnud\u00f3 completamente mientras sub\u00eda la escalera y los vecinos la atrapan infraganti con el culo al aire. Ella escapa.","og_url":"https:\/\/blog.argxp.com\/es_es\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/","url":"https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/","name":"Bella y sola: Julieta, la acompa\u00f1ante milagrosa Parte 2","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-02-26T20:37:52+00:00","description":"Julieta se desnud\u00f3 completamente mientras sub\u00eda la escalera y los vecinos la atrapan infraganti con el culo al aire. Ella escapa.","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/it\/blog\/bella-y-sola-julieta-la-acompanante-milagrosa-pt-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"Bella y sola: Julieta, la acompa\u00f1ante milagrosa &#8211; Pt. 2"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/es_es\/wp-json\/wp\/v2\/blog\/50598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/es_es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/es_es\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/es_es\/wp-json\/wp\/v2\/media?parent=50598"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/es_es\/wp-json\/wp\/v2\/blog-categoria?post=50598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}