{"id":59866,"date":"2021-08-20T15:30:00","date_gmt":"2021-08-20T18:30:00","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=59866"},"modified":"2021-08-20T15:30:00","modified_gmt":"2021-08-20T18:30:00","slug":"cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/fr\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/","title":{"rendered":"Cabarets \u00e0 Buenos Aires \u2013 Diego Ruiz partage ses histoires"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Dans l&#039;histoire de l&#039;art qui entoure les racines du tango et du divertissement en Argentine ; les c\u00e9l\u00e9brit\u00e9s sont \u00e0 l&#039;honneur <strong>cabaret \u00e0 Buenos Aires<\/strong>. De pr\u00e9cieux \u00e9difices o\u00f9 prosp\u00e9raient les orchestres ; jazz et boissons entre amis ou partenaires c\u00e9libataires qui se sont rencontr\u00e9s pour une nuit de divertissement parmi des r\u00e9miniscences distingu\u00e9es du luxe \u00e9tranger.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aujourd&#039;hui le <strong>Cabarets de Buenos Aires<\/strong> ils ont \u00e9volu\u00e9 pour devenir de nouveaux centres de divertissement plus modernes, mais leurs racines demeurent et sont port\u00e9es \u00e0 la connaissance populaire parmi les mythes et les v\u00e9rit\u00e9s dites\u00a0; parmi de nombreux professionnels, par le mus\u00e9ologue et \u00e9crivain Diego Ruiz ; qui s&#039;est consacr\u00e9 \u00e0 parcourir les anciennes all\u00e9es de la m\u00e9moire en sauvant les histoires de certains des<strong> vieux cabarets de Buenos Aires<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Beaucoup d&#039;entre eux ont \u00e9t\u00e9 ferm\u00e9s et d\u00e9molis il y a plus d&#039;un si\u00e8cle, mais l&#039;expression artistique du tango et de certains films ; en plus des \u0153uvres th\u00e9\u00e2trales pr\u00e9dominantes \u00e0 cette \u00e9poque, elles ont immortalis\u00e9 l&#039;atmosph\u00e8re d&#039;\u00e9l\u00e9gance qu&#039;un vaste public ressentait dans ces lieux ; souvent accompagn\u00e9s de belles femmes en robes de satin pour \u00e9gayer la soir\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par cons\u00e9quent, aujourd&#039;hui, nous allons faire un tour de l&#039;histoire de certains des <strong>c\u00e9l\u00e8bres cabarets de Buenos Aires<\/strong>, assaisonn\u00e9 de quelques-unes des chroniques de Diego Ruiz et sa reconstruction de quelques faits curieux \u00e0 leur sujet.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-locales-que-dieron-inicio-a-los-cabarets-de-buenos-aires\">Les lieux qui ont donn\u00e9 naissance aux cabarets de Buenos Aires<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">On ignore beaucoup de choses sur l&#039;histoire populaire des anciens lieux qui favorisaient les divertissements nocturnes; car ils n&#039;avaient laiss\u00e9 aucune trace visible apr\u00e8s leur disparition.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais quand il s&#039;agit de <strong>Cabaret \u00e0 Buenos Aires<\/strong> on d\u00e9couvre que la soci\u00e9t\u00e9 ne les a pas laiss\u00e9s aussi loin qu&#039;on aurait pu s&#039;y attendre ; et dans certaines histoires et contes compil\u00e9s par Diego Ruiz \u00e0 partir de chacun d&#039;eux, la merveille de ces environnements sociaux peut encore \u00eatre appr\u00e9ci\u00e9e; qui constituait \u00e9galement une source principale d&#039;emploi pour certains des orchestres ou groupes musicaux les plus acclam\u00e9s de l&#039;\u00e9poque.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D&#039;une part, gr\u00e2ce \u00e0 la bonne musique que beaucoup d&#039;hommes seuls ou de couples \u00e9coutaient \u00e0 certaines heures d&#039;ouverture au public, la <strong>Cabaret \u00e0 Buenos Aires<\/strong> ils se sont distingu\u00e9s; en fonction de la reconnaissance du groupe qui y \u00e9tait pr\u00e9sent\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#039;est pourquoi, \u00e0 cette \u00e9poque, les \u00e9v\u00e9nements qui se d\u00e9roulaient tous les soirs dans les Cabarets ; ils \u00e9taient la source de revenus la plus stable que les musiciens bien connus pouvaient trouver. Parce que, bien s\u00fbr, les soir\u00e9es dans les cabarets se composaient r\u00e9guli\u00e8rement de nourriture et de boissons servies par des \u00e9chansons ; qui a encourag\u00e9 les hommes c\u00e9libataires \u00e0 continuer \u00e0 profiter de la nuit et \u00e0 danser jusqu&#039;\u00e0 l&#039;aube.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/blog.argxp.com\/wp-content\/uploads\/2025\/05\/Cabarets-en-Buenos-Aires-800x619.jpg\" alt=\"Cabaret \u00e0 Buenos Aires\" class=\"wp-image-59889\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Cabaret \u00e0 Buenos Aires<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Donc, si vous faites partie de ceux qui aiment un bon endroit pour s&#039;amuser, vous avez s\u00fbrement voulu visiter l&#039;un des endroits. Ainsi, vous ne pouvez pas manquer l&#039;histoire conserv\u00e9e par certains des plus c\u00e9l\u00e8bres <strong>Cabaret \u00e0 Buenos Aires<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comme le &quot;Chantecler&quot; qui a ouvert ses portes pour la premi\u00e8re fois en d\u00e9cembre 1924, et en est l&#039;un des exemplaires les plus r\u00e9cents. Des orchestres c\u00e9l\u00e8bres comme celui de Juan D&#039;Arienzo s&#039;y sont produits et son nom a re\u00e7u le titre du tango compos\u00e9 par Enrique Cad\u00edcamo \u00ab Adi\u00f3s Chantecler \u00bb apr\u00e8s sa d\u00e9molition en 1960.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais qu&#039;est-il arriv\u00e9 aux autres ?<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-vel-dromo-hansen\">V\u00e9lodrome (Hansen)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">C&#039;est probablement le cabaret avec la plus longue histoire connue, il y a plusieurs anecdotes qui s&#039;y d\u00e9roulent. Initialement appel\u00e9 Hansen, fr\u00e9quent\u00e9 par Ernesto Ponzio, Juan Carlos Baz\u00e1n et Luis Teisseire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il fut d&#039;abord l&#039;un des premiers <strong>Cabaret \u00e0 Buenos Aires<\/strong>, que hac\u00eda las veces de restaurante con m\u00fasica para ambientar la noche. El local conocido como Hansen, nombrado por \u00faltima vez \u00abRestaurante Palermo\u00bb, fue demolido en 1912; para pasar a formar parte del acceso que llegaba al aqu\u00ed nombrado Vel\u00f3dromo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon les histoires que Diego Ruiz recueille \u00e0 propos de cet endroit, beaucoup de choses se sont pass\u00e9es dans ces salles. Comme \u00e7a vous ne pouviez pas danser dans ce Cabaret gr\u00e2ce \u00e0 une interdiction municipale ou que le propri\u00e9taire ait d\u00fb une fois interdire la repr\u00e9sentation d&#039;El Esquinazo, car l&#039;humeur des clients \u00e9tait tellement enflamm\u00e9e par la pr\u00e9sentation que la destruction de la vaisselle et des verres \u00e9tait presque in\u00e9vitable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On raconte aussi que Baz\u00e1n jouait aux abords du V\u00e9lodrome avec sa clarinette et incitait le public \u00e0 entrer dans l&#039;\u00e9tablissement. Apr\u00e8s le succ\u00e8s de son petit tour, les partenaires locaux lui ont offert deux pesos pour chaque membre de son groupe ; plus de nourriture et de pourboires et c&#039;est ainsi que lui et ses compagnons sont devenus partie int\u00e9grante de l&#039;animation officielle du V\u00e9lodrome.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-armenonville\">armenonville<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">C&#039;\u00e9tait un luxueux <strong>cabaret \u00e0 Buenos Aires<\/strong>  qu&#039;il privil\u00e9giait une image anglaise m\u00eame si la nourriture qu&#039;il offrait \u00e9tait d&#039;origine fran\u00e7aise. Il \u00e9tait situ\u00e9 sur l&#039;Avenida Alvear \u00e0 Tagle, Palerme et avait une piste de danse d\u00e9cor\u00e9e de miroirs et de grands jardins qui en faisaient un lieu fr\u00e9quent\u00e9 par les gens de la classe sup\u00e9rieure.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 sa d\u00e9molition en 1929, Armenonville n&#039;est pas seulement connu comme un cabaret de renom ; mais plut\u00f4t, o\u00f9 Carlos Gardel a \u00e9t\u00e9 abattu lors d&#039;un combat qui l&#039;a laiss\u00e9 en convalescence pendant un moment.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/blog.argxp.com\/wp-content\/uploads\/2025\/05\/Carlos-Gardel-fue-herido-de-bala-800x534.jpg\" alt=\"Carlos Gardel a \u00e9t\u00e9 abattu\" class=\"wp-image-59890\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-tabaris\">Tabaris<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tabaris a succ\u00e9d\u00e9 \u00e0 un autre <strong>cabaret \u00e0 Buenos Aires<\/strong>, remarquable de l&#039;\u00e9poque comme l&#039;\u00e9tait le Royal Pigall, apr\u00e8s sa d\u00e9molition en 1920. Situ\u00e9 \u00e0 Corrientes 825, le Tarabis devint l&#039;un des cabarets les plus importants de l&#039;\u00e9poque, il poss\u00e9dait une piste de danse et des cabines derri\u00e8re des rideaux de verre de velours rouge o\u00f9 les hommes pu s&#039;amuser en compagnie de <a href=\"https:\/\/argentinaxp.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">escortes de luxe<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il s&#039;est distingu\u00e9 comme \u00e9tant le premier \u00e9tablissement \u00e0 disposer de la climatisation et plus tard en 1937. Comme le Teatro-Dancin Tarabi, il a \u00e9t\u00e9 remodel\u00e9 pour s&#039;adapter \u00e0 un style plus moderne. Les locaux ont \u00e9t\u00e9 vendus et transform\u00e9s \u00e0 diff\u00e9rentes occasions. Plus tard, il a \u00e9t\u00e9 repris dans le cadre du circuit de th\u00e9\u00e2tre Rottenberg en 2006.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-conclusi-n\">conclusion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">l&#039;histoire de <strong>cabaret \u00e0 Buenos Aires<\/strong> c&#039;est complexe et pas exactement expos\u00e9 \u00e0 trouver. Mais passionn\u00e9s par cette ancienne r\u00e9miniscence comme Diego Ruiz, ils exhument ces morceaux de culture perdue qui font partie de l&#039;essence argentine la plus vivante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Certains de ces cabarets ont favoris\u00e9 la pr\u00e9sence des charmantes milongas aujourd&#039;hui associ\u00e9es \u00e0 la <a href=\"https:\/\/argentinaxp.com\/escorts-capital-federal\/\" target=\"_blank\" rel=\"noreferrer noopener\">escortes CABA<\/a> que nous savons Pour cette raison, l&#039;histoire de ces centres de la vie nocturne fait partie des nuances qui entourent leur monde et aujourd&#039;hui nous sommes pr\u00eats \u00e0 vous apprendre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si vous voulez en savoir plus sur le <strong><a href=\"https:\/\/argentinaxp.com\/blog\/cabarets-portenos-nostalgia-de-buenos-aires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cabaret de Buenos Aires<\/a><\/strong> ou des lieux d&#039;int\u00e9r\u00eat tels que le centenaire <strong><a href=\"https:\/\/argentinaxp.com\/blog\/spa-colmegna-un-pedazo-de-la-antigua-roma-en-buenos-aires\/\" target=\"_blank\" rel=\"noreferrer noopener\">Spa Colmegna<\/a><\/strong>, visitez notre blog et d\u00e9couvrez tout ce que vous devez savoir pour profiter pleinement du monde de <a href=\"https:\/\/argentinaxp.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Escortes VIP<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h2>Table des mati\u00e8res<\/h2><ul><li><a href=\"#h-locales-que-dieron-inicio-a-los-cabarets-de-buenos-aires\" data-level=\"2\">Les lieux qui ont donn\u00e9 naissance aux cabarets de Buenos Aires<\/a><ul><li><a href=\"#h-vel-dromo-hansen\" data-level=\"3\">V\u00e9lodrome (Hansen)<\/a><\/li><li><a href=\"#h-armenonville\" data-level=\"3\">armenonville<\/a><\/li><li><a href=\"#h-tabaris\" data-level=\"3\">Tabaris<\/a><\/li><\/ul><\/li><li><a href=\"#h-conclusi-n\" data-level=\"2\">conclusion<\/a><\/li><\/ul><\/div>","protected":false},"featured_media":59888,"template":"","blog-categoria":[43],"class_list":["post-59866","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-historia-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cabarets en Buenos Aires - Diego Ruiz comparte sus historias<\/title>\n<meta name=\"description\" content=\"\u00bfConoces acerca de la historia de los Cabarets en Buenos Aires? Diego Ruiz comparte sus historias acerca de estos fant\u00e1sticos lugares de anta\u00f1o.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cabarets en Buenos Aires - Diego Ruiz comparte sus historias\" \/>\n<meta property=\"og:description\" content=\"\u00bfConoces acerca de la historia de los Cabarets en Buenos Aires? Diego Ruiz comparte sus historias acerca de estos fant\u00e1sticos lugares de anta\u00f1o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/fr\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/\",\"name\":\"Cabarets en Buenos Aires - Diego Ruiz comparte sus historias\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2021-08-20T18:30:00+00:00\",\"description\":\"\u00bfConoces acerca de la historia de los Cabarets en Buenos Aires? Diego Ruiz comparte sus historias acerca de estos fant\u00e1sticos lugares de anta\u00f1o.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/\"]}],\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cabarets en Buenos Aires &#8211; Diego Ruiz comparte sus historias\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cabarets \u00e0 Buenos Aires - Diego Ruiz partage ses histoires","description":"Connaissez-vous l&#039;histoire du Cabaret de Buenos Aires ? Diego Ruiz partage ses histoires sur ces lieux fantastiques d&#039;antan.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Cabarets en Buenos Aires - Diego Ruiz comparte sus historias","og_description":"\u00bfConoces acerca de la historia de los Cabarets en Buenos Aires? Diego Ruiz comparte sus historias acerca de estos fant\u00e1sticos lugares de anta\u00f1o.","og_url":"https:\/\/blog.argxp.com\/fr\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/","url":"https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/","name":"Cabarets \u00e0 Buenos Aires - Diego Ruiz partage ses histoires","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/#primaryimage"},"thumbnailUrl":"","datePublished":"2021-08-20T18:30:00+00:00","description":"Connaissez-vous l&#039;histoire du Cabaret de Buenos Aires ? Diego Ruiz partage ses histoires sur ces lieux fantastiques d&#039;antan.","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/"]}],"accessibilityFeature":["tableOfContents"]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/en\/blog\/cabarets-en-buenos-aires-diego-ruiz-comparte-sus-historias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"Cabarets en Buenos Aires &#8211; Diego Ruiz comparte sus historias"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog\/59866","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/media?parent=59866"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog-categoria?post=59866"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}