{"id":90163,"date":"2022-08-20T19:03:48","date_gmt":"2022-08-20T22:03:48","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=90163"},"modified":"2022-08-20T19:03:48","modified_gmt":"2022-08-20T22:03:48","slug":"bonjour-papa","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/fr\/blog\/hola-papuchi\/","title":{"rendered":"BONJOUR PAPA! (Partie II)"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Contrairement \u00e0 ce \u00e0 quoi il s&#039;attendait, il s&#039;endormit rapidement. Mais contrairement \u00e0 tant d&#039;autres milliers de nuits, cette fois <a href=\"https:\/\/argentinaxp.com\/blog\/sueno-sexual\/\">r\u00eav\u00e9 d&#039;une femme<\/a> sans visage qui l&#039;a soumis \u00e0 un v\u00e9ritable marathon sexuel. Il se r\u00e9veilla plusieurs fois, effray\u00e9, pour se remettre \u00e0 somnoler et \u00eatre visit\u00e9 par les m\u00eames r\u00eaveries, extr\u00eamement r\u00e9alistes. A chaque fois, il constatait qu&#039;il avait une \u00e9rection de la plus haute importance, mais il n&#039;\u00e9tait plus capable de faire la distinction entre ce qui \u00e9tait r\u00eav\u00e9 et ce qui \u00e9tait r\u00e9el. C&#039;est ainsi qu&#039;une des nuits les plus \u00e9tranges de sa vie se passa. Jusqu&#039;au matin venu et il \u00e9couta presque avec soulagement le son aga\u00e7ant du r\u00e9veil lui disant qu&#039;il devait recommencer sa routine.<br \/>Parce que ce qu&#039;il ne savait pas, c&#039;est que la veille n&#039;\u00e9tait que le d\u00e9but d&#039;une s\u00e9rie de jours de torture. Tant au bureau que dans son service, les appels du sexopathe inconnu se sont succ\u00e9d\u00e9s, avant les r\u00e9primandes r\u00e9p\u00e9t\u00e9es du patron alors qu&#039;ils \u00e9taient pendant les heures de travail. Aussi fatigu\u00e9 qu&#039;effray\u00e9, il a rassembl\u00e9 tout le courage qu&#039;il n&#039;avait jamais eu et a d\u00e9cid\u00e9 de signaler l&#039;incident au poste de police local. Il ne dormait presque plus, il perdait l&#039;app\u00e9tit et s&#039;affaiblissait consid\u00e9rablement \u00e0 cause de l&#039;angoisse provoqu\u00e9e par les communications flamboyantes de l&#039;inconnue, dont l&#039;ardeur augmentait au fil des jours.<br \/>Devant le regard narquois de l&#039;officier de service, rougissant jusqu&#039;\u00e0 la honte et b\u00e9gayant comme une mitraillette, il porte plainte pour &quot;harc\u00e8lement ind\u00e9cent&quot; au commissariat, esp\u00e9rant au plus profond de son c\u0153ur que cela suffirait \u00e0 mettre fin \u00e0 cela. supplice. Mais \u00e7a c&#039;est pas pass\u00e9 comme \u00e7a. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tard apr\u00e8s midi, nuit apr\u00e8s nuit, la communication unilat\u00e9rale se r\u00e9p\u00e9ta, jusqu&#039;au bout d&#039;une semaine Gregorio crut atteindre les sommets de la panique, lorsqu&#039;il entendit : \u00ab Papuchito\u2026 le jour est enfin arriv\u00e9 ; Demain nous nous verrons, oui ou oui, et je vais te montrer le ciel, ma ch\u00e8vre. Pr\u00e9parez la baignoire, retirez les affaires du dessus du placard, accrochez la balan\u00e7oire et laissez tous les jouets \u00e0 port\u00e9e de main, la f\u00eate commence. Oh, je compte les minutes jusqu&#039;\u00e0 ce que je te sente en moi, petite chose ! OK au revoir; Repose-toi bien, tu vas en avoir besoin, ma ch\u00e9rie.&quot;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br \/>Cela a rempli le pauvre Gregorio. Le lendemain\u2026 et il n&#039;a pas pr\u00e9cis\u00e9 le lieu, ni l&#039;heure, pour le pire. Apr\u00e8s une nuit de cauchemar et une journ\u00e9e au bureau \u00e0 attendre le t\u00e9l\u00e9phone (qui cette fois ne sonne pas !), le pauvre diable quitte l&#039;entreprise, plus terrifi\u00e9 que jamais. Se souvenir du plaisir torturant qu&#039;il ressentait pendant des instants dans les r\u00eaves lubriques que lui causaient les appels ne suffisait pas \u00e0 compenser la panique qu&#039;il ressentait \u00e0 l&#039;\u00e9ventualit\u00e9 d&#039;une rencontre avec une femme aussi ardente et inconnue. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces choses n&#039;\u00e9taient pas pour lui. Il avait le vague espoir que la Police avait organis\u00e9, comme promis, une garde \u00e0 vue devant chez lui. Mais c&#039;\u00e9tait tr\u00e8s peu probable, \u00e0 en juger par le sarcasme avec lequel ils ont pris la plainte. En effet; aucun homme en uniforme n&#039;a \u00e9t\u00e9 vu dans les environs.<br \/>Que ce soit ce que Dieu veut !, pensa-t-il entre ses r\u00e2les, en s&#039;approchant de chez lui. Elle entra dans l&#039;immeuble aussi prudemment que possible, tituba dans le couloir crasseux et finit par trouver le courage d&#039;entrer dans l&#039;appartement. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La porte s&#039;ouvrit de force et elle sentit son c\u0153ur s&#039;arr\u00eater. En entrant, et avant qu&#039;il ne puisse faire quoi que ce soit, il a vu les lumi\u00e8res aveuglantes des projecteurs et des cam\u00e9ras de t\u00e9l\u00e9vision se poser sur la silhouette imposante d&#039;une femme blonde prodigieuse, \u00e0 peine v\u00eatue d&#039;une minuscule et transparente &quot;Baby Doll&quot;, qui portait une bouteille de champagne. dans sa main droite et s&#039;approcha de lui en lui disant : &quot;Bonjour, papuchi, tu es l&#039;heureux gagnant de <strong>SEXE EXPRESS<\/strong>, le concours qui r\u00e9alise vos r\u00eaves \u00e9rotiques. Nous te choisissons parmi cinq mille candidats anonymes pour que tu puisses passer la nuit de tes r\u00eaves avec moi. Enl\u00e8ve tout et viens te coucher, on va filmer pour la cha\u00eene EROTIC SHOCK, qui sponsorise tout \u00e7a. Ils te verront partout dans le monde, tigre ! Et les lumi\u00e8res tomb\u00e8rent sur lui, tandis que la femme se jeta sur lui et le couvrit de baisers.<br \/>Ce furent les derniers mots que Gregorio entendit avant de s&#039;\u00e9vanouir et de tomber \u00e0 plat sur le sol. De l\u00e0, aux soins intensifs de l&#039;h\u00f4pital le plus proche, suite \u00e0 un arr\u00eat cardiaque, puis au cimeti\u00e8re, car quelques jours plus tard, il mourut sans pouvoir se remettre du choc fatal de la vue de cette femme, ni du stress de ces jours-l\u00e0, et sans comprendre ce qui se passait. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Que si : la cha\u00eene Erotic Sock payait tous les frais de l&#039;hospitalisation et de l&#039;enterrement.<\/p>","protected":false},"featured_media":90165,"template":"","blog-categoria":[44],"class_list":["post-90163","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-relatos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>hola papuchi<\/title>\n<meta name=\"description\" content=\"Si escuchas &quot;hola papuchi&quot; en el tel\u00e9fono, cuidado. La &quot;telerrealidad&quot; puede trastocarlo todo. (Segunda parte - Relato er\u00f3tico)\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"hola papuchi\" \/>\n<meta property=\"og:description\" content=\"Si escuchas &quot;hola papuchi&quot; en el tel\u00e9fono, cuidado. La &quot;telerrealidad&quot; puede trastocarlo todo. (Segunda parte - Relato er\u00f3tico)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/fr\/blog\/bonjour-papa\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/\",\"name\":\"hola papuchi\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-08-20T22:03:48+00:00\",\"description\":\"Si escuchas \\\"hola papuchi\\\" en el tel\u00e9fono, cuidado. La \\\"telerrealidad\\\" puede trastocarlo todo. (Segunda parte - Relato er\u00f3tico)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/en\\\/blog\\\/hello-daddy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00a1HOLA PAPUCHI! (Parte II)\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bonjour papa","description":"Si vous entendez &quot;hello papuchi&quot; au t\u00e9l\u00e9phone, faites attention. La &quot;t\u00e9l\u00e9r\u00e9alit\u00e9&quot; peut tout chambouler. (Deuxi\u00e8me partie - Histoire \u00e9rotique)","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"hola papuchi","og_description":"Si escuchas \"hola papuchi\" en el tel\u00e9fono, cuidado. La \"telerrealidad\" puede trastocarlo todo. (Segunda parte - Relato er\u00f3tico)","og_url":"https:\/\/blog.argxp.com\/fr\/blog\/bonjour-papa\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/","url":"https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/","name":"Bonjour papa","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-08-20T22:03:48+00:00","description":"Si vous entendez &quot;hello papuchi&quot; au t\u00e9l\u00e9phone, faites attention. La &quot;t\u00e9l\u00e9r\u00e9alit\u00e9&quot; peut tout chambouler. (Deuxi\u00e8me partie - Histoire \u00e9rotique)","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/en\/blog\/hello-daddy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"\u00a1HOLA PAPUCHI! (Parte II)"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog\/90163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/media?parent=90163"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog-categoria?post=90163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}