{"id":93538,"date":"2022-09-08T13:11:22","date_gmt":"2022-09-08T16:11:22","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=93538"},"modified":"2022-09-08T13:11:22","modified_gmt":"2022-09-08T16:11:22","slug":"a-los-pies","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/fr\/blog\/a-los-pies\/","title":{"rendered":"AUX PIEDS DE SOFIA"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Il m&#039;arrive toujours la m\u00eame chose, d\u00e8s que la chaleur arrive. Je commence \u00e0 marcher les yeux vers le sol plus que d&#039;habitude : je regarde les pieds des femmes, qui commencent \u00e0 se d\u00e9couvrir apr\u00e8s le confinement hivernal. En observant les membres inf\u00e9rieurs f\u00e9minins, et sans m&#039;en rendre compte, je pense comment cette femme sera intimement. C&#039;est comme si je la d\u00e9shabillais de bas en haut, pour ensuite en tirer des conclusions qui ne sont m\u00eame pas claires pour moi. Je n&#039;ai jamais l&#039;impression de conna\u00eetre une dame \u00e0 fond si je n&#039;ai pas pu <a href=\"https:\/\/argentinaxp.com\/blog\/fetiche-de-pies-por-que-nos-encantan-los-pies-de-las-escorts\/\">\u00e9tudiant secr\u00e8tement ses pieds. <\/a><br \/>Et c&#039;est ce qui m&#039;a d\u00e9rang\u00e9 chez Sof\u00eda, la nouvelle coll\u00e8gue qui est arriv\u00e9e dans notre entreprise un apr\u00e8s-midi de printemps. Elle \u00e9tait charmante, blonde et propri\u00e9taire d&#039;un regard innocent. Il ne nous a pas fallu longtemps pour nous entendre, et apr\u00e8s une semaine de connaissance, il \u00e9tait rare que nous ne sortions pas ensemble pour prendre un caf\u00e9 ou d\u00e9jeuner apr\u00e8s chaque jour de semaine.<br \/>C&#039;\u00e9tait une fascination mutuelle. Nous avons pass\u00e9 des heures \u00e0 parler, et en moins de quinze jours, il m&#039;avait racont\u00e9 toute sa jeune vie. Au fait, j&#039;avais \u00e9t\u00e9 tout aussi confiant, ouvrant mon c\u0153ur comme jamais auparavant. Tout semblait parfait, et il se dirigeait vers une idylle heureuse ou une de ces amiti\u00e9s qu&#039;on voit rarement entre hommes et femmes. Cependant, il y avait quelque chose qui me d\u00e9rangeait profond\u00e9ment.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-revelacion\">R\u00e9v\u00e9lation<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il m&#039;a fallu un certain temps pour comprendre ce que c&#039;\u00e9tait, jusqu&#039;\u00e0 ce qu&#039;un jour chaud de novembre j&#039;ai d\u00e9couvert : depuis que je l&#039;ai rencontr\u00e9e, je n&#039;avais jamais vu ses pieds. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cette \u00e9poque, il \u00e9tait d\u00e9j\u00e0 habituel pour moi de me vautrer, comme chaque ann\u00e9e, dans l&#039;observation inconsciente des membres inf\u00e9rieurs de chaque femme qui se trouvait. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais ce n&#039;\u00e9tait pas le cas de Sofia. Je ne l&#039;avais jamais vue sans bottines ferm\u00e9es, ni chaussures fines et fonc\u00e9es, ni avec des pantoufles sophistiqu\u00e9es. Mais jamais pieds nus. Au d\u00e9but, j&#039;ai minimis\u00e9 cette question. De m\u00eame, il les a imagin\u00e9s selon son grand corps. Elles auraient des doigts plut\u00f4t fins, des ongles manucur\u00e9s et des talons comme du velours. Mais le probl\u00e8me non r\u00e9solu \u00e9tait toujours dans ma t\u00eate. Que faire? Notre relation m\u00fbrissait, et dans ses yeux couleur de miel, je semblais remarquer qu&#039;il attendait de moi quelque chose de plus que de bavarder autour d&#039;un caf\u00e9 et d&#039;une agr\u00e9able compagnie. Mais il m&#039;\u00e9tait presque impossible de penser \u00e0 en faire ma partenaire si je ne r\u00e9v\u00e9lais pas d&#039;abord ce dernier myst\u00e8re : ses pieds.<br \/>Tout s&#039;est pr\u00e9cipit\u00e9 d\u00e9but d\u00e9cembre, quand apr\u00e8s avoir pris un caf\u00e9 devant le bureau, nous nous sommes promen\u00e9s un moment dans le parc. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La conversation se passait bien, bien qu&#039;elle soit tendue, comme si elle n&#039;osait pas me dire quelque chose. Finalement, elle a r\u00e9ussi \u00e0 aller droit au but : elle m&#039;a dit qu&#039;elle \u00e9tait amoureuse de moi. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-final-en-los-pies\">Une fin sur les pieds<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La premi\u00e8re impulsion que j&#039;ai ressentie a \u00e9t\u00e9 de l&#039;embrasser passionn\u00e9ment. Mais quelque chose m&#039;en emp\u00eachait. Je savais ce que c&#039;\u00e9tait, mais j&#039;ai refus\u00e9 de l&#039;accepter. Finalement, je n&#039;ai pas pu me contenir : les yeux embu\u00e9s, je me suis accroupi et, \u00e0 sa stupeur, j&#039;ai pratiquement arrach\u00e9 ses chaussures. Elle a \u00e9t\u00e9 laiss\u00e9e pieds nus et embarrass\u00e9e, me regardant d&#039;un air vide et montrant involontairement ses membres d\u00e9licats, qui \u00e9taient exactement comme je les avais imagin\u00e9s. Je restai \u00e0 genoux, contemplant ses membres inf\u00e9rieurs, les yeux \u00e9carquill\u00e9s et l&#039;esprit bloqu\u00e9. Apr\u00e8s quelques interminables secondes, elle attrapa ses chaussures et se mit \u00e0 courir. Je ne l&#039;ai plus revue.<br \/>Le lendemain, un t\u00e9l\u00e9gramme froid nous informa qu&#039;il ne travaillerait plus avec nous. Et j&#039;ai appris que lors d&#039;un appel t\u00e9l\u00e9phonique, il avait dit \u00e0 notre patron qu&#039;il ne voulait pas avoir de coll\u00e8gues d\u00e9rang\u00e9s.<br \/>Peut-\u00eatre que j&#039;ai perdu la femme de ma vie ; je ne sais pas. Maintenant, je fais une th\u00e9rapie et mon analyste pense que la mienne n&#039;est pas s\u00e9rieuse. Mais je suppose qu&#039;il ne comprend pas; Sofia non plus. Je continue \u00e0 regarder les pieds f\u00e9minins comme si de rien n&#039;\u00e9tait.<\/p>","protected":false},"featured_media":93554,"template":"","blog-categoria":[44],"class_list":["post-93538","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-relatos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A los pies<\/title>\n<meta name=\"description\" content=\"Caer a los pies de Sof\u00eda no fue una elecci\u00f3n, fue inevitable. Muchas veces, los deseos m\u00e1s profundos se pelean con la felicidad.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A los pies\" \/>\n<meta property=\"og:description\" content=\"Caer a los pies de Sof\u00eda no fue una elecci\u00f3n, fue inevitable. Muchas veces, los deseos m\u00e1s profundos se pelean con la felicidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/fr\/blog\/a-los-pies\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/\",\"name\":\"A los pies\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-09-08T16:11:22+00:00\",\"description\":\"Caer a los pies de Sof\u00eda no fue una elecci\u00f3n, fue inevitable. Muchas veces, los deseos m\u00e1s profundos se pelean con la felicidad.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/a-los-pies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A LOS PIES DE SOF\u00cdA\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aux pieds","description":"Tomber aux pieds de Sofia n&#039;\u00e9tait pas un choix, c&#039;\u00e9tait in\u00e9vitable. Souvent, les d\u00e9sirs les plus profonds se battent avec bonheur.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"A los pies","og_description":"Caer a los pies de Sof\u00eda no fue una elecci\u00f3n, fue inevitable. Muchas veces, los deseos m\u00e1s profundos se pelean con la felicidad.","og_url":"https:\/\/blog.argxp.com\/fr\/blog\/a-los-pies\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/","url":"https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/","name":"Aux pieds","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-09-08T16:11:22+00:00","description":"Tomber aux pieds de Sofia n&#039;\u00e9tait pas un choix, c&#039;\u00e9tait in\u00e9vitable. Souvent, les d\u00e9sirs les plus profonds se battent avec bonheur.","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/it\/blog\/a-los-pies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"A LOS PIES DE SOF\u00cdA"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog\/93538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/media?parent=93538"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/fr\/wp-json\/wp\/v2\/blog-categoria?post=93538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}