{"id":46310,"date":"2020-11-11T17:05:03","date_gmt":"2020-11-11T20:05:03","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=46310"},"modified":"2020-11-11T17:05:03","modified_gmt":"2020-11-11T20:05:03","slug":"acompanante-sexual-que-conquisto-al-rey","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/","title":{"rendered":"Madame de Pompadour, compagna sessuale intellettuale di Luigi XV"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Madame de Pompadour era una donna traboccante di bellezza ed eleganza. Una signora dell&#039;alta borghesia finanziaria entr\u00f2 per la prima volta a Versailles con il magnifico obiettivo di conquistare il cuore del re. Riusc\u00ec a raggiungere, come desiderava, essere un compagno sessuale e intellettuale di Luigi XV.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/argentinaxp.com\/wp-content\/uploads\/2020\/11\/14-800x671.png\" alt=\"Compagno di Luigi XV, Madame de Pompadour\" class=\"wp-image-46621\"\/><figcaption>Ritratto di Madame de Pompadour<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Jeanne-Antoinette Poisson, con la sua immensa volont\u00e0 politica, entr\u00f2 in conflitto con l&#039;alta aristocrazia francese, senza tuttavia abbandonare il suo onorevole lavoro di compagna sessuale del re fino ai suoi ultimi giorni.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-su-infancia\">La sua infanzia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sua madre era Louise Madeleine De La Motte e suo padre, Lenormant de Tourenhem, nacque a Parigi il 29 dicembre 1721.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suo padre deve essere fuggito in Germania accusato di affari fraudolenti. Ma nonostante il flusso di scandali al riguardo, Reinette ha ricevuto un&#039;educazione buona e squisita.&nbsp;<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-de-ama-de-casa-a-acompa-ante-real\"><strong>Da casalinga a compagna reale<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Costretta dal padre a sposare sua cugina poco pi\u00f9 che ventenne, ha avuto un figlio un anno dopo e una figlia pochi anni dopo. Suo marito Charles-Guillaume Lenormand d&#039;\u00c9tiolles era perdutamente innamorato di sua moglie e profondamente incantato dalla sua bellezza abbagliante.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La futura compagna sessuale del re pi\u00f9 importante, per curiose ragioni, nella storia dell&#039;Occidente, inizi\u00f2 a frequentare la societ\u00e0 alto borghese di Parigi. Inizi\u00f2 cos\u00ec a frequentare le alte sale della societ\u00e0 del suo tempo. La preziosa signora venne a conoscere personaggi storici noti, come gli incredibili filosofi del suo tempo, vale a dire il francese Voltaire, o il barone de Montesquieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuttavia, la semplice vita borghese sembrava annoiare Madame de Pompadour ed \u00e8 cos\u00ec che nel 1745 i suoi piani cambiarono. Nella sua sensuale seduzione, ha proposto la folle idea di conquistare il cuore nientemeno che del re di Francia. A dire il vero, \u00e8 un mistero come questa dama sia riuscita a salire per entrare nella Reggia di Versailles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Senza sangue aristocratico, \u00e8 riuscita a penetrare in quel mondo reale e, sebbene non si sappia perch\u00e9, sospettiamo ardentemente che la sua bellezza abbia qualcosa a che fare con questo.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jeanne-Antoinette ha lanciato il suo folle piano, ha dovuto incrociare la strada con il re nelle sue ripetute battute di caccia nella foresta di S\u00e9nart.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luigi XV inizi\u00f2 a prestare attenzione a quella misteriosa dama ed \u00e8 in quello stesso anno che ottenne un incontro privato con Madame d&#039;\u00c9tiolles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Purtroppo il marito della signora, affranto, ha dovuto separarsi legalmente dalla moglie. La dama che gli spezz\u00f2 il cuore ora accompagnava il re, che le diede il titolo nobilissimo di Madame de Pompadour.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-poissonnades-acompa-ante-real\"><strong>poissonnades<\/strong>, compagno reale<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/argentinaxp.com\/wp-content\/uploads\/2020\/11\/11-800x671.png\" alt=\"Ritratto di Luigi XV\" class=\"wp-image-46622\"\/><figcaption>Ritratto di Luigi XV<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Fu allora, il 14 settembre 1745, che Madame de Pompadour fu presentata pubblicamente al palazzo di Versailles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Era la prima volta in Francia che una dama di origine borghese riusciva ad occupare, contro ogni previsione, la grande posizione di favorita della casa reale. Come il lettore pu\u00f2 immaginare, la corte e l&#039;aristocrazia in generale non solo voltarono le spalle alla bella dama, ma si rivoltarono anche contro di lei.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I figli di Luigi XV non parlavano con la loro nuova padrona. Quelli pi\u00f9 vicini al re cercarono di persuadere il loro monarca dell&#039;errore che il suo rapporto con una signora di origine borghese implicava per loro.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una pluralit\u00e0 di satire furono fatte contro di lei e furono conosciute come <em>poissonnades<\/em>, in riferimento al suo cognome, Poisson. Vale la pena dire che \u00e8 simile alla parola &quot;veleno&quot; in inglese, il cui significato \u00e8 veleno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma che importava a Reinette delle accuse e delle critiche?! Con il favore del re, le provocazioni non ebbero effetto su di lei. Ha continuato a influenzare in modo decisivo il marito, diventando cos\u00ec non solo la sua amante, ma anche uno dei suoi consiglieri reali. In questo modo mise in atto la sua strategia e inizi\u00f2 a sbarazzarsi di coloro che gli si opponevano e interrompevano il suo brillante cammino.<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-pompadour-dama-intelectual\"><strong>pompadour<\/strong>, signora intellettuale<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Promotrice dell&#039;Enciclopedia di Diderot, inizi\u00f2 a sostenere vari progetti artistici, distinguendosi come una signora non solo molto sensuale, ma anche profondamente colta. Ha contribuito a produrre opere pittoriche o monumenti di Boucher come Place de la Concorde a Parigi, Jeanne-Antoinette era una delle principali mecenate dell&#039;epoca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per chiarezza del lettore, il patrocinio \u00e8 il compito di sponsorizzare e finanziare vari talenti. In questo caso, la dama di compagnia del re, che era gi\u00e0 molto di pi\u00f9, ha contribuito allo splendore artistico della Francia del XVIII secolo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La marchesa fece trasferire a S\u00e8vres la fabbrica di porcellane Meissen e ne fece il punto di riferimento per gli oggetti decorativi e di lusso in tutta Europa. L\u00ec fu creato il colore noto come Rosa Pompadour in onore del patrono reale.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel meraviglioso Campo di Dio Marte a Parigi, Jeanne-Antoine fece costruire un istituto appositamente dedicato all&#039;educazione dei giovani soldati, che avrebbe dato origine alla Scuola Militare dell&#039;edificio David.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/argentinaxp.com\/wp-content\/uploads\/2020\/11\/13-800x671.png\" alt=\"Madame de Pompadour\" class=\"wp-image-46623\"\/><\/figure>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-de-amante-a-compa-era\"><strong>Da amante a partner<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Per cinque anni Madame de Pompadour ebbe rapporti intimi con Luigi XV interpretando il suo ruolo di compagno sessuale. Cos\u00ec, partendo dal suo nobile lavoro, finirebbe per trascorrere con lui niente di pi\u00f9 e niente di meno che 20 anni; come confidente, amico e ambasciatore d&#039;arte, oltre che imprenditore di vari progetti.&nbsp;<\/p>\n\n\n\n<h2 class=\"has-text-align-center wp-block-heading\" id=\"h-la-guerra-de-los-siete-a-os-y-el-fin-de-la-marquesa\"><strong>La Guerra dei Sette Anni e la fine della Marchesa<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durante il periodo in cui fu al fianco del re, Madame de Pompadour non smise di lavorare come consigliere politico. Nel 1756 inizi\u00f2 la Guerra dei Sette Anni dove la Francia si schier\u00f2 con l&#039;Austria e la Russia contro la Prussia e l&#039;Inghilterra. Di chiara opposizione al re prussiano Federico II, Madame de Pompadour intervenne presso il conte di Kaunitz, che fu cancelliere e ministro degli esteri del famoso <strong><a href=\"http:\/\/grandesmujeresenlahistoria.blogspot.com\/2011\/03\/la-madre-de-sus-pueblos-maria-teresa-de.html\">Maria Teresa d&#039;Austria<\/a>. <\/strong>stavo cercando<strong> <\/strong>accettare un&#039;alleanza con questo paese. Tuttavia, l&#039;aristocrazia parigina, contraria agli austriaci, non avrebbe mai perdonato il movimento politico di Giovanna Antonietta.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il suo ruolo nelle trattative con l&#039;Austria fu utilizzato dalla nobilt\u00e0 per continuare la loro campagna contro il compagno del re. Tuttavia ha continuato sempre a testa alta e ad impegnarsi nelle cose che la interessavano, fino alla sua ultima ora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Font<\/strong>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.mujeresenlahistoria.com\/2011\/06\/la-amante-burguesa-madame-de-pompadour.html\" target=\"_blank\" rel=\"noreferrer noopener\">donne nella storia<\/a><\/p>","protected":false},"featured_media":46619,"template":"","blog-categoria":[43],"class_list":["post-46310","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-historia-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La acompa\u00f1ante sexual que conquist\u00f3 al rey de Francia<\/title>\n<meta name=\"description\" content=\"Madame de Pompadour - Todo lo que deseas saber sobre la acompa\u00f1ante sexual y dama intelecutal de Luis XV, rey de Francia\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La acompa\u00f1ante sexual que conquist\u00f3 al rey de Francia\" \/>\n<meta property=\"og:description\" content=\"Madame de Pompadour - Todo lo que deseas saber sobre la acompa\u00f1ante sexual y dama intelecutal de Luis XV, rey de Francia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/\",\"name\":\"La acompa\u00f1ante sexual que conquist\u00f3 al rey de Francia\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-11-11T20:05:03+00:00\",\"description\":\"Madame de Pompadour - Todo lo que deseas saber sobre la acompa\u00f1ante sexual y dama intelecutal de Luis XV, rey de Francia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/acompanante-sexual-que-conquisto-al-rey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madame de Pompadour, la acompa\u00f1ante intelectual sexual de Luis XV\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il compagno sessuale che conquist\u00f2 il re di Francia","description":"Madame de Pompadour - Tutto quello che volevi sapere sulla compagna sessuale e signora intellettuale di Luigi XV, re di Francia","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"La acompa\u00f1ante sexual que conquist\u00f3 al rey de Francia","og_description":"Madame de Pompadour - Todo lo que deseas saber sobre la acompa\u00f1ante sexual y dama intelecutal de Luis XV, rey de Francia","og_url":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/","url":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/","name":"Il compagno sessuale che conquist\u00f2 il re di Francia","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-11-11T20:05:03+00:00","description":"Madame de Pompadour - Tutto quello che volevi sapere sulla compagna sessuale e signora intellettuale di Luigi XV, re di Francia","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/it\/blog\/acompanante-sexual-que-conquisto-al-rey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"Madame de Pompadour, la acompa\u00f1ante intelectual sexual de Luis XV"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog\/46310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/media?parent=46310"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog-categoria?post=46310"}],"curies":[{"name":"buona partita","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}