{"id":76516,"date":"2022-07-16T23:20:15","date_gmt":"2022-07-17T02:20:15","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=76516"},"modified":"2022-07-16T23:20:15","modified_gmt":"2022-07-17T02:20:15","slug":"la-casa-redonda-una-gran-mansion","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/it\/blog\/la-casa-redonda-una-gran-mansion\/","title":{"rendered":"The Round House - una grande villa"},"content":{"rendered":"<p class=\"wp-block-paragraph\">I vicini si chiedono di chi sia e perch\u00e9 sia chiuso da anni. Non \u00e8 una casa qualsiasi, ma un grande palazzo liberty in perfette condizioni. Si trova in una zona residenziale di Buenos Aires. \u00c8 conosciuta come The Round House, tuttavia, si sa poco di questa residenza privata, con il suo misterioso passato e presente.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/blog.argxp.com\/wp-content\/uploads\/2025\/05\/ZDCO3LRFEVCTVLPT4V2B5Y3BMI-800x533.webp\" alt=\"The Round House - una grande villa\" class=\"wp-image-87311\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Costruzione del grande palazzo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La costruzione di La Casa Redonda, un grande palazzo, non passa inosservata. La sua torre e il colorato stile italiano hanno poco a che fare con le case in stile Tudor e i piccoli hotel della zona. La sua posizione \u00e8 strategica, sta producendo ochava nelle strade Eduardo Costa e Ort\u00edz de Ocampo, nel Barrio Parque, di fronte al viale Figueroa Alcorta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secondo i documenti che danno conto dell&#039;opera del pittore e architetto Palanti in Argentina, l&#039;emblematico palazzo fu inaugurato nel 1922. Anche Chrysler fu opera di Palanti. Sul lato sud di questa enorme costruzione si trova La Redonda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/blog.argxp.com\/wp-content\/uploads\/2025\/05\/YYZQEOVHRBATBFKJ5SX6V4HUHU-800x533.webp\" alt=\"The Round House - una grande villa\" class=\"wp-image-87312\"\/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Mario Palanti architetto di La Casa Redonda, un grande palazzo<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Si narra che l&#039;architetto costru\u00ec il grande palazzo di fronte alla concessionaria in modo che la famiglia Fevre, rappresentante della Chrysler in Argentina, potesse osservare dalle finestre della propria abitazione la pista di prova per auto che l&#039;edificio aveva all&#039;ultimo piano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#039;\u00e8 chi, contemplando questo gioiello architettonico della citt\u00e0 di Buenos Aires, ricorda subito un altro tesoro di Buenos Aires: il Palacio Barolo. I dati non sorprendono se teniamo conto che l&#039;autore di entrambe le costruzioni \u00e8 lo stesso. Mario Palanti ha sviluppato la sua formazione accademica nel suo paese natale, ma gran parte della sua eredit\u00e0 \u00e8 rimasta in Argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arriv\u00f2 a Buenos Aires giovanissimo, a soli 25 anni, con l&#039;obiettivo di partecipare alla costruzione del Padiglione Italia. Quello sarebbe diventato l&#039;inizio di quella che fu per lui una brillante carriera, segno del suo grande talento e creativit\u00e0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/blog.argxp.com\/wp-content\/uploads\/2025\/05\/K4FQEYMHGJD43PPJF6M3EPL5AU-800x533.webp\" alt=\"The Round House - una grande villa\" class=\"wp-image-87313\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Se ti fermi sul marciapiede di Figueroa Alcorta, puoi vedere la sua torre di vedetta sinuosa in stile indiano spiccare tra le cime degli alberi di jacaranda. Presenta una ringhiera in muratura dalla quale si alza una paletta in ferro. Inoltre, i cancelli mostrano rilievi lignei che, per molti, evocano Dante, autore della Divina Commedia, e Beatrice, la sua protagonista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00c8 indubbiamente palantino, dalle basi bulbose e sovradimensionate dei balconi, all&#039;evocazione medioevale italiana dei ballatoi e tutti gli ornamenti sicuramente unici, pensati e realizzati proprio per questa casa, come le lanterne nel giardino, le intaglio delle porte, ecc.\u201d, descrive Espina Rawson.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-un-fantasma-en-la-casa-redonda-una-gran-y-misteriosa-mansion\">Un fantasma nella Round House- Una villa grande e misteriosa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nel corso della sua storia, \u00e8 passato attraverso diversi proprietari. Tra il 1940 e il 1949 La Casa Redonda, un grande palazzo, fu abitata dalla famiglia Ceballos. Finch\u00e9 l\u00ec una delle figlie mor\u00ec di tubercolosi e si trasferirono all&#039;Hotel Savoy. Pi\u00f9 tardi, una famiglia di Salta lo us\u00f2 durante i loro soggiorni a Buenos Aires. \u00c8 stata anche l&#039;ambasciata dell&#039;Iran fino al 1979, quando Shah Mohammad Reza Pahlavi era ancora al potere. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ecco perch\u00e9 \u00e8 stato rivelato che ha un bunker di sicurezza registrato, piastre di rimbalzo, sistemi contro le armi automatiche e finestre di sicurezza e sorveglianza. Poi l&#039;acquist\u00f2 la famiglia Fucile, che per quattro anni si dedic\u00f2 a restaurarla poich\u00e9 era in cattive condizioni. Hanno vissuto l\u00ec fino al 1998 quando l&#039;hanno venduto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rimase chiuso per anni fino a quando l&#039;azienda argentina Mobili decise di affittarlo e investire una grossa somma di denaro per restaurarlo e allestire uno showroom di mobili di lusso dove erano esposte anche opere d&#039;arte. Hanno occupato il posto per circa due anni e da allora \u00e8 stato chiuso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vicky Pel\u00e1ez, che era la curatrice di quella mostra, ricorda quanto fosse lussuoso il palazzo all&#039;interno: &quot;Al piano terra c&#039;erano boiserie, un grande camino e una scala importante&quot;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L&#039;enigmatica Round House: una grande dimora piena di segreti<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Come si \u00e8 scoperto, il proprietario di La Redonda \u00e8 argentino e vive all&#039;estero. La casa intanto resta di notte con le luci spente, non ci sono campanelli o citofoni elettrici in vista e si distingue solo un&#039;insegna con il numero, quello di Eduardo Costa 3079, pur avendo un ingresso da entrambe le strade. Si trova all&#039;interno di un&#039;area protetta chiamata APH 3 Grand Bourg, un&#039;area tranquilla con diagonali in stile parigino progettata da Carlos Thays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A sua volta, uno dei clienti che era solito andare a comprare i mobili sul sito, ha rivelato che all&#039;interno stavano accadendo cose strane in quel momento. \u201cLe luci si sono accese da sole, l&#039;allarme ha suonato, le immagini si sono mosse e gli oggetti sono caduti dall&#039;alto delle scale. Nel quartiere si diceva che vi abitasse il fantasma dell&#039;autista dei primi abitanti, che all&#039;inizio del secolo mor\u00ec a causa di un incidente all&#039;interno della casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Secondo il sito interattivo del governo di Buenos Aires, Ciudad3D, dove appare con il numero 3083, la residenza ha una superficie edificata di 810 m\u00b2, mentre il terreno ha 466 m\u00b2. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si sviluppa su due piani ed \u00e8 classificato come Patrimonio Architettonico e Urbano della Citt\u00e0, con tutela strutturale, in quanto, ai sensi della Legge 3056, trattandosi di edificio antecedente al 1941, non pu\u00f2 essere demolito o modificato. Tuttavia, il rapporto non dice nulla sui suoi attuali proprietari. &quot;Speriamo che presto inizi a muoversi, \u00e8 triste vedere una casa cos\u00ec bella, chiusa&quot;, dicono i vicini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Puoi visitare il Barrio Parque accompagnato dalla Round House, se vuoi un bel <a href=\"https:\/\/argentinaxp.com\/\">scorta<\/a>. Barrio Parque \u00e8 una zona scelta da diverse personalit\u00e0 importanti: giudici, artisti e politici si rifugiano nelle dimore in stile inglese e francese che si moltiplicano lungo le strade curve. Sono case basse e imponenti opere architettoniche.<\/p>","protected":false},"featured_media":87310,"template":"","blog-categoria":[46],"class_list":["post-76516","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-turismo-escorts-argentina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Casa Redonda - una gran mansi\u00f3n ubicada en una zona residencial<\/title>\n<meta name=\"description\" content=\"Hablaremos de la casa redonda, gran y hermosa mansi\u00f3n ubicada en una zona residencial en Buenos Aires, pero actualmente cerrada.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Casa Redonda - una gran mansi\u00f3n ubicada en una zona residencial\" \/>\n<meta property=\"og:description\" content=\"Hablaremos de la casa redonda, gran y hermosa mansi\u00f3n ubicada en una zona residencial en Buenos Aires, pero actualmente cerrada.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/it\/blog\/la-casa-redonda-una-gran-mansion\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/\",\"name\":\"La Casa Redonda - una gran mansi\u00f3n ubicada en una zona residencial\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-07-17T02:20:15+00:00\",\"description\":\"Hablaremos de la casa redonda, gran y hermosa mansi\u00f3n ubicada en una zona residencial en Buenos Aires, pero actualmente cerrada.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/ru\\\/blog\\\/la-casa-redonda-una-gran-mansion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La casa Redonda &#8211; una gran mansi\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Round House - un grande palazzo situato in una zona residenziale","description":"Parleremo della casa rotonda, un grande e bellissimo palazzo situato in una zona residenziale di Buenos Aires, ma attualmente chiuso.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"La Casa Redonda - una gran mansi\u00f3n ubicada en una zona residencial","og_description":"Hablaremos de la casa redonda, gran y hermosa mansi\u00f3n ubicada en una zona residencial en Buenos Aires, pero actualmente cerrada.","og_url":"https:\/\/blog.argxp.com\/it\/blog\/la-casa-redonda-una-gran-mansion\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/","url":"https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/","name":"The Round House - un grande palazzo situato in una zona residenziale","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-07-17T02:20:15+00:00","description":"Parleremo della casa rotonda, un grande e bellissimo palazzo situato in una zona residenziale di Buenos Aires, ma attualmente chiuso.","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/ru\/blog\/la-casa-redonda-una-gran-mansion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"La casa Redonda &#8211; una gran mansi\u00f3n"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog\/76516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/media?parent=76516"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog-categoria?post=76516"}],"curies":[{"name":"buona partita","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}