{"id":87334,"date":"2022-07-18T15:55:31","date_gmt":"2022-07-18T18:55:31","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=87334"},"modified":"2022-07-18T15:55:31","modified_gmt":"2022-07-18T18:55:31","slug":"masters-y-johnson-los-gurus-de-una-revolucion-sexual","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/","title":{"rendered":"Masters e Johnson, i guru di una rivoluzione sessuale."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Los a\u00f1os 60&#8242; del siglo pasado fueron una \u00e9poca revulsiva, qu\u00e9 duda cabe. Rebeldes como pocas veces, las masas (particularmente los j\u00f3venes) se opon\u00edan a casi todo lo que tuviera forma de obligaci\u00f3n impuesta por el Estado o sus socios corporativos. Una de sus \u00abmarcas registradas\u00bb fue el trabajo de la pareja de sex\u00f3logos Masters y Johnson, claros gu\u00edas de la respuesta sexual humana.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hipismo, el rock de aquellos tiempos (ya lejos de sus primeras manifestaciones, como Elvis Presley o Bill Haley y lanzado a la m\u00e1s feroz experimentaci\u00f3n)  las drogas alucin\u00f3genas, el rechazo a la guerra de Vietnam, el peligro de la \u00abguerra fr\u00eda\u00bb, el asesinato de John F. Kennedy y dem\u00e1s hechos revulsivos, configuraban un panorama de \u00abantes y despu\u00e9s\u00bb. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposito, i comportamenti sessuali non sono stati esclusi e hanno avuto la loro rivoluzione. All&#039;enorme allentamento delle abitudini amorose che ha promosso i movimenti giovanili, si \u00e8 aggiunta la divulgazione della pillola contraccettiva. Creato nel 1956 e 10 anni dopo contava diversi milioni di consumatori in tutta l&#039;America. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-toda-revolucion-tiene-sus-guias\">Ogni rivoluzione ha le sue guide<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La coppia&nbsp;<strong>Guglielmo Maestri<\/strong>&nbsp;Y&nbsp;<strong>Virginia Johnson&nbsp;<\/strong>sono stati indubbiamente i sessuologi pi\u00f9 apprezzati del secolo scorso, grazie alle loro ricerche sul&nbsp;<strong>risposta sessuale umana<\/strong>. I suoi libri erano Bestseller e avevano una visibilit\u00e0 paragonabile a quella delle Rock star. E una capacit\u00e0 simile di scioccare l&#039;establishment. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una delle principali scoperte di questo studio \u00e8 stata la scoperta del ruolo fondamentale del clitoride nell&#039;orgasmo femminile. Fino ad allora, l&#039;idea freudiana dell &#039;&quot;orgasmo vaginale&quot; predominava come ideale di <a href=\"https:\/\/argentinaxp.com\/blog\/mentiras-del-orgasmo-conoce-las-verdades-y-mentiras-mas-comunes-del-tema\/\">orgasmo<\/a>. La ricerca di Masters e Johnson, i guru di una rivoluzione al suo apice, ha dimostrato che la stimolazione vaginale non era molto rilevante per l&#039;orgasmo femminile. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue as\u00ed que \u00abpusieron en valor\u00bb un \u00f3rgano que hab\u00eda sido descubierto por el anatomista y cirujano Mateo Renaldo Col\u00f3n, en la Italia del siglo XVI. Eso le vali\u00f3 la persecuci\u00f3n inquisitorial, porque dijo que ese ap\u00e9ndice no ten\u00eda m\u00e1s utilidad que provocar placer. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En realidad, su \u00abdescubrimiento\u00bb, por llamarlo de alguna manera, tambi\u00e9n se lo atribuyen otros dos anatomistas de la \u00e9poca. Y un historiador contempor\u00e1neo a estos cient\u00edficos manifiesta que en realidad al cl\u00edtoris se lo conoce desde el siglo II. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Comunque lo erano <strong>Guglielmo Maestri<\/strong>&nbsp;Y&nbsp;<strong>Virginia Johnson<\/strong> che gli ha dato popolarit\u00e0, utilizzando i gi\u00e0 molto massicci media dell&#039;epoca. Un altro dei suoi contributi \u00e8 stato essere i genitori di <strong>terapie sessuali e consulenza sessuologica<\/strong> tal como las conocemos hoy.  Por eso se los considera \u00ablos gur\u00fas de la revoluci\u00f3n sexual\u00bb<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-respuesta-sexual-humana\">\u00abLa respuesta sexual humana\u00bb<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tale era il titolo del libro che ha cambiato la visione del sesso in Occidente. E siccome non stavano mai fermi, gi\u00e0 in et\u00e0 avanzata (nel 1994) pubblicarono un altro volume che a 28 anni di distanza dal primo gli diede un altro approccio. <strong>\u00abHeterosexualidad\u00bb<\/strong>, d\u00e1ndole a su trabajo una visi\u00f3n desde un plano m\u00e1s \u00abafectivo\u00bb y contemplando las emociones. Algo muy distinto al muy fisiol\u00f3gico de su obra m\u00e1s famosa. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In generale, il modello di terapia sessuale di Masters e Johnson divideva la risposta sessuale umana in 4 fasi principali: <strong>fase di eccitazione, fase di plateau, fase orgasmica e fase di risoluzione. <\/strong>Differivano dal metodo di Alfred Kinsey, il padre della ricerca sessuale. Questo scienziato, negli anni &#039;40 e &#039;50 del secolo scorso, ha pubblicato rapporti sul comportamento sessuale umano,<strong> <\/strong>basato solo su interviste che ha fatto con dozzine di persone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Masters e Johnson hanno fatto qualcosa di completamente diverso. Con scandalo di molti, questa coppia di guru della rivoluzione sessuale (lei psicologa, il ginecologo) \u00e8 andata ben oltre: ha preso appunti sulle reazioni dei volontari che hanno accettato di farsi analizzare nel bel mezzo dell&#039;atto sessuale. Hanno registrato i tempi. Gli elettrodi sono stati attaccati a coppie di amanti per monitorarli meglio mentre avevano rapporti in un laboratorio. Hanno usato elettrocardiografi, vibratori, macchine fotografiche, ecc. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Attraverso questi metodi (che gli valsero l&#039;appellativo di pervertiti, guardoni e peggio) e le conclusioni che ne trassero, Masters e Johnson furono un punto cardine nella ricerca sul sesso e sulla sua percezione nel mondo occidentale. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-el-legado\">L&#039;EREDIT\u00c0<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de su obra m\u00e1s conocida, \u00abLa respuesta sexual humana\u00bb (1966), estos gur\u00fas de la revoluci\u00f3n sexual publicaron \u00abIncompatibilidad sexual humana\u00bb (1970), \u00abEl v\u00ednculo del placer\u00bb (1975), y la ya mencionada \u00abHeterosexualidad\u00bb (1994). Todas fueron obras fundamentales de la sexolog\u00eda y grandes bestsellers. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00abSimplemente, quiero responder una pregunta:<\/strong>&nbsp;<strong>\u00bfqu\u00e9 ocurre en el cuerpo durante el sexo?\u00bb<\/strong>disse Virginia Johnson. Hanno risposto che e anche <strong>hanno demolito miti, istruito e migliorato la vita sessuale delle persone<\/strong>, todo contra los prejuicios de la \u00e9poca. No solo por un tab\u00fa moral: la comunidad cient\u00edfica no consideraba el sexo como objeto de estudio muy v\u00e1lido o interesante, hasta que llegaron ellos. Como bien se dijo, \u00absacaron el sexo de la alcoba y lo pusieron en el laboratorio\u00bb. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oggi, quando quasi tutti i pregiudizi sono caduti ed entrambi <a href=\"https:\/\/argentinaxp.com\/escortsvip\">accompagnatori indipendenti<\/a> Poich\u00e9 le donne di ogni ceto sociale danno e ricevono piacere sessuale senza grossi problemi, \u00e8 bene ricordare coloro che hanno fatto molto per renderlo possibile. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guglielmo Maestri<\/strong>&nbsp;scomparso nel 2001, all&#039;et\u00e0 di 85 anni, e&nbsp;<strong>Virginia Johnson<\/strong> nel 2013, con 88. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"featured_media":87391,"template":"","blog-categoria":[43],"class_list":["post-87334","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-historia-e-historias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gur\u00fas de la revoluci\u00f3n sexual<\/title>\n<meta name=\"description\" content=\"En la d\u00e9cada de los a\u00f1os 60 del siglo pasado, dos gur\u00fas de la revoluci\u00f3n sexual cambiaron para siempre la percepci\u00f3n del sexo en occidente.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gur\u00fas de la revoluci\u00f3n sexual\" \/>\n<meta property=\"og:description\" content=\"En la d\u00e9cada de los a\u00f1os 60 del siglo pasado, dos gur\u00fas de la revoluci\u00f3n sexual cambiaron para siempre la percepci\u00f3n del sexo en occidente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/\",\"name\":\"Gur\u00fas de la revoluci\u00f3n sexual\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-07-18T18:55:31+00:00\",\"description\":\"En la d\u00e9cada de los a\u00f1os 60 del siglo pasado, dos gur\u00fas de la revoluci\u00f3n sexual cambiaron para siempre la percepci\u00f3n del sexo en occidente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Masters\u00a0y Johnson, los gur\u00fas de una revoluci\u00f3n sexual.\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guru della rivoluzione sessuale","description":"Negli anni &#039;60, due guru della rivoluzione sessuale hanno cambiato per sempre la percezione del sesso in Occidente.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Gur\u00fas de la revoluci\u00f3n sexual","og_description":"En la d\u00e9cada de los a\u00f1os 60 del siglo pasado, dos gur\u00fas de la revoluci\u00f3n sexual cambiaron para siempre la percepci\u00f3n del sexo en occidente.","og_url":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/","url":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/","name":"Guru della rivoluzione sessuale","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-07-18T18:55:31+00:00","description":"Negli anni &#039;60, due guru della rivoluzione sessuale hanno cambiato per sempre la percezione del sesso in Occidente.","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/it\/blog\/masters-y-johnson-los-gurus-de-una-revolucion-sexual\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"Masters\u00a0y Johnson, los gur\u00fas de una revoluci\u00f3n sexual."}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog\/87334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/media?parent=87334"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/it\/wp-json\/wp\/v2\/blog-categoria?post=87334"}],"curies":[{"name":"buona partita","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}