{"id":80195,"date":"2022-05-02T12:00:00","date_gmt":"2022-05-02T15:00:00","guid":{"rendered":"https:\/\/argentinaxp.com\/?post_type=blog&#038;p=80195"},"modified":"2022-05-02T12:00:00","modified_gmt":"2022-05-02T15:00:00","slug":"angela-white","status":"publish","type":"blog","link":"https:\/\/blog.argxp.com\/zh\/blog\/angela-white\/","title":{"rendered":"\u5b89\u5409\u62c9\u6000\u7279"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>\u5b89\u5409\u62c9\u6000\u7279 <\/strong>\u5979\u662f\u4e00\u540d\u5973\u6f14\u5458\u517c\u8272\u60c5\u7247\u5bfc\u6f14\uff0c2003 \u5e74\u56e0\u62cd\u6444\u6210\u4eba\u7535\u5f71\u800c\u51fa\u9053\uff1b\u5979\u4e8e 2013 \u5e74\u5f00\u901a\u4e86\u4e2a\u4eba\u7f51\u7ad9\uff0c\u9664\u4e86\u662f\u4e00\u540d\u5973\u6f14\u5458\uff0c\u5979\u8fd8\u662f\u4e00\u540d\u6d3b\u8dc3\u7684 camgirl\u3002\u7531\u4e8e\u5979\u8ff7\u4eba\u7684\u66f2\u7ebf\u3001\u72c2\u91ce\u7684\u6027\u60c5\u548c\u5927\u80c6\u7684\u6027\u7231\u573a\u9762\uff0c\u8fd9\u4f4d\u4ee4\u4eba\u60ca\u53f9\u7684\u6fb3\u5927\u5229\u4e9a\u8272\u60c5\u5973\u661f\u5f81\u670d\u4e86\u6210\u4eba\u7535\u5f71\u4e1a\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-biografia\">\u4f20<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u5b89\u5409\u62c9\u6000\u7279 <\/strong>\u4efb\u4f55\u4e00\u4e2a <strong>\u5b89\u742a<\/strong>\u662f\u6fb3\u5927\u5229\u4e9a\u7535\u5f71\u754c\u6700\u6210\u529f\u3001\u6700\u5177\u5f71\u54cd\u529b\u7684\u5973\u6f14\u5458\u548c\u5bfc\u6f14\uff0c\u66fe\u63a8\u51fa\u591a\u90e8\u6210\u4eba\u7535\u5f71\u30021985 \u5e74 3 \u6708 4 \u65e5\u51fa\u751f\u4e8e\u6fb3\u5927\u5229\u4e9a\u65b0\u5357\u5a01\u5c14\u58eb\u5dde\u6089\u5c3c\u5e02\u3002\u5b89\u5409\u62c9\u51fa\u8eab\u4e8e\u4e00\u4e2a\u5bcc\u88d5\u7684\u5bb6\u5ead\uff0c\u6bcd\u4eb2\u662f\u4e00\u540d\u6444\u5f71\u5e08\uff0c\u7236\u4eb2\u662f\u4e00\u540d\u6728\u5320\u3002<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5979 8 \u5c81\u4e4b\u524d\u4e00\u76f4\u4f4f\u5728\u6089\u5c3c\u5185\u57ce\uff0c\u540e\u6765\u642c\u5230\u7ef4\u591a\u5229\u4e9a\u5dde\u7684\u4e00\u4e2a\u519c\u573a\uff0c\u9ad8\u4e2d\u65f6\u53c8\u968f\u5bb6\u4eba\u7b2c\u4e8c\u6b21\u642c\u5230\u6fb3\u5927\u5229\u4e9a\u4e1c\u6d77\u5cb8\u300214 \u5c81\u65f6\uff0c\u5979\u4e0e\u4e00\u540d\u7537\u5b69\u5931\u8eab\uff0c\u4e0d\u4e45\u540e\u516c\u5f00\u8868\u793a\u81ea\u5df1\u662f\u53cc\u6027\u604b\u3002&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/blog.argxp.com\/wp-content\/uploads\/2025\/05\/Angela-White-pornstar-1-800x517.jpg\" alt=\"\u5b89\u5409\u62c9\u6000\u7279\u8272\u60c5\u660e\u661f\" class=\"wp-image-80201\"\/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u5728\u4e2d\u5b66\uff0c <strong>\u5b89\u742a<\/strong> \u66fe\u5728\u6c49\u5821\u738b\u548c\u5927\u536b-\u743c\u65af\uff08David Jones\uff09\u517c\u804c\u30022003 \u5e74\uff0c18 \u5c81\u7684\u5979\u5f00\u59cb\u4ece\u4e8b\u88f8\u4f53\u6a21\u7279\u5de5\u4f5c\uff0c\u5f53\u65f6\u5979\u8fd8\u5728\u4e0a\u9ad8\u4e2d\u3002\u8fc7\u4e86\u4e00\u6bb5\u65f6\u95f4\u540e\uff0c\u5979\u4e8e 2011 \u5e74\u5f00\u59cb\u62cd\u6444\u9732\u70b9\u955c\u5934\uff0c\u591a\u5e74\u6765\uff0c\u5979\u7684\u51fa\u8272\u8868\u73b0\u4e3a\u5979\u5728 AVN \u540d\u4eba\u5802\u4e2d\u8d62\u5f97\u4e86\u4e00\u5e2d\u4e4b\u5730\u3002&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u5979\u770b\u8d77\u6765\u7f8e\u6781\u4e86 <a href=\"https:\/\/argentinaxp.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u8d35\u5bbe\u62a4\u9001<\/a><strong> <\/strong>\u73b0\u5e74 37 \u5c81\uff0c\u8eab\u6750\u59e3\u597d\uff0c\u80f8\u90e8\u81ea\u7136\u4e30\u6ee1\uff0c\u8eab\u9ad8 5 \u82f1\u5c3a 7 \u82f1\u5bf8\uff08\u7ea6\u5408 167 \u5398\u7c73\uff09\uff0c\u4f53\u91cd 60 \u516c\u65a4\uff08\u7ea6\u5408 132 \u78c5\uff09\u3002\u5979\u7684\u8eab\u9ad8\u4e3a 107- 69- 104 \u5398\u7c73\uff0c\u6709\u4e00\u53cc\u7f8e\u4e3d\u7684\u84dd\u773c\u775b\uff0c\u9ed1\u5934\u53d1\uff0c\u767d\u76ae\u80a4\u3002<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-instruccion-academica-de-angela-white\">\u5b89\u5409\u62c9-\u6000\u7279\u7684\u5b66\u672f\u6307\u5bfc<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se gradu\u00f3 con honores en la Universidad de Melbourne en estudios de g\u00e9nero en el 2010. En su tesis, presento una investigaci\u00f3n cualitativa sobre las experiencias femeninas en la industria de la pornograf\u00eda australiana; en agosto de 2017, los hallazgos de la tesis de honor de Angela se publicaron como un cap\u00edtulo titulado \u00abEl actor porno\u00bb en The Routledge Companion to Media, Sex and Sexuality.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-trayectoria-adulta\">\u6210\u5e74\u8f68\u8ff9&nbsp;<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u5b89\u742a <\/strong>hizo sus primeras escenas de sexo en 2003 para la producci\u00f3n de Score Group \u00abun d\u00eda con Angela White\u00bb, dirigida por Tushna. Asimismo, produce y dirige escenas para adultos y todav\u00eda filma escenas porno. Hasta la fecha, esta australiana es muy conocida en la industria PornStar, ganado m\u00e1s de 80 distinguidos premios de la industria y ha sido nominada a m\u00e1s de 100.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-carrera-politica-de-angela-white\">\u5b89\u5409\u62c9-\u6000\u7279\u7684\u653f\u6cbb\u751f\u6daf<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">2010 \u5e74\uff0c\u5979\u4f5c\u4e3a\u6fb3\u5927\u5229\u4e9a\u6027\u7231\u515a\uff08Australian Sex Party\uff09\u7684\u653f\u6cbb\u5019\u9009\u4eba\u53c2\u52a0\u4e86\u7ef4\u591a\u5229\u4e9a\u5dde\u7684\u7ade\u9009\uff0c\u4ee5\u4e89\u53d6\u6027\u5de5\u4f5c\u8005\u7684\u6743\u5229\u3002\u5728\u7ade\u9009\u671f\u95f4\uff0c\u5979\u5411\u603b\u68c0\u5bdf\u957f\u7f57\u5e03-\u80e1\u5c14\u65af\uff08Rob Hulls\uff09\u5bc4\u9001\u4e86\u81ea\u5df1\u7684 DVD\uff0c\u4ee5\u51cf\u5c11\u5bf9 X \u7ea7\u7535\u5f71\u7684\u76d1\u7ba1\uff0c\u4ece\u800c\u83b7\u5f97\u4e86\u6781\u5927\u7684\u66dd\u5149\u7387\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-salario-de-angela-white\">\u5b89\u5409\u62c9\u00b7\u6000\u7279\u85aa\u6c34<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u5f53\u4ed6\u5f00\u529e\u81ea\u5df1\u7684\u6210\u4eba\u5236\u4f5c\u516c\u53f8\u65f6<strong> \u5b89\u5409\u62c9\u00b7\u6000\u7279\u5236\u4f5c\u516c\u53f8<\/strong>\uff0c\u8fd9\u4f4d\u7f8e\u4e3d\u7684\u5973\u4eba\u62e5\u6709\u7f8e\u56fd$ 4500\u4e07\u7684\u8eab\u5bb6\u3002<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-premios-de-angela-white\">\u5b89\u5409\u62c9\u6000\u7279\u5956&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">\u5728\u5979\u7684\u804c\u4e1a\u751f\u6daf\u4e2d\uff0c\u5b89\u5409\u62c9-\u6000\u7279\u66fe\u56e0\u5176\u5728\u6210\u4eba\u7535\u5f71\u4e1a\u7684\u4e13\u4e1a\u8868\u73b0\u83b7\u5f97\u591a\u9879\u63d0\u540d\u548c\u5956\u9879\uff0c\u5305\u62ec\u6700\u4f73\u5973\u6f14\u5458\uff08XBIZ \u5956--2010 \u5e74\uff09\u3001\u5e74\u5ea6\u575a\u5b88\u6f14\u5458\uff08Score margazine \u5956--2011 \u5e74\uff09\u3001\u6700\u4f73\u6027\u7231\u573a\u666f\uff08XBIZ \u5956--2012 \u5e74\uff09\u548c\u5e74\u5ea6\u6700\u4f73\u5973\u6f14\u5458\uff08AVN \u5956--2016 \u5e74\u30012019 \u5e74\u548c 2020 \u5e74\uff09\u3002<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/blog.argxp.com\/wp-content\/uploads\/2025\/05\/Angela-White-actriz-800x470.jpg\" alt=\"\u5b89\u5409\u62c9\u00b7\u6000\u7279 \u6f14\u5458\" class=\"wp-image-80198\"\/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-filmografia-de-angela-white\">\u5b89\u5409\u62c9\u00b7\u6000\u7279\u7684\u5f71\u89c6\u4f5c\u54c1&nbsp;<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>\u4e0e\u5b89\u5409\u62c9\u00b7\u6000\u7279\u7684\u4e00\u5929 (2003)\u3002&nbsp;<\/li><li>\u5b89\u5409\u62c9\uff082014 \u5e74\uff09\u3002<\/li><li>\u5b89\u5409\u62c9\u559c\u6b22\u4e09\u4eba\u884c\uff082015\uff09\u3002&nbsp;<\/li><li>\u5b89\u5409\u62c9\u7231\u5947\u95fb\u8da3\u4e8b (2016)\u3002<\/li><li>\u5b89\u5409\u62c9\u7231\u5973\u4eba 2 (2016)\u3002<\/li><li>\u5b89\u5409\u62c9-\u6000\u7279\u662f\u300a\u4f18\u96c5\u5929\u4f7f\u300b\uff082017 \u5e74\uff09\u7684\u5973\u4e3b\u89d2\u3002<\/li><li>\u6211\u662f\u5b89\u5409\u62c9-\"\u90aa\u6076\u5929\u4f7f\"\uff082018 \u5e74\uff09\u3002<\/li><li>\u5b89\u5409\u62c9\u7231\u5973\u4eba 5 (2019)\u3002<\/li><li>\u5b89\u5409\u62c9\u00b7\u6000\u7279\uff1a\u9ed1\u6697\u9762\uff08\u6731\u5c14\u65af\u00b7\u4e54\u4e39\uff09(2019)\u3002<\/li><li>\u9a76\u5411 \"\u66f4\u6df1\u5904\"\uff082019 \u5e74\uff09\u3002<\/li><li>\u6210\u4eba\u65f6\u95f4\u89c6\u89d2\uff082019 \u5e74\uff09\u3002<\/li><\/ul>\n\n\n\n<div class=\"wp-block-yoast-seo-table-of-contents yoast-table-of-contents\"><h2>\u76ee\u5f55<\/h2><ul><li><a href=\"#h-biografia\" data-level=\"2\">\u4f20<\/a><ul><li><a href=\"#h-instruccion-academica-de-angela-white\" data-level=\"3\">\u5b89\u5409\u62c9-\u6000\u7279\u7684\u5b66\u672f\u6307\u5bfc<\/a><\/li><li><a href=\"#h-trayectoria-adulta\" data-level=\"3\">\u6210\u5e74\u8f68\u8ff9&nbsp;<\/a><\/li><li><a href=\"#h-carrera-politica-de-angela-white\" data-level=\"3\">\u5b89\u5409\u62c9-\u6000\u7279\u7684\u653f\u6cbb\u751f\u6daf<\/a><\/li><\/ul><\/li><li><a href=\"#h-salario-de-angela-white\" data-level=\"2\">\u5b89\u5409\u62c9\u00b7\u6000\u7279\u85aa\u6c34<\/a><\/li><li><a href=\"#h-premios-de-angela-white\" data-level=\"2\">\u5b89\u5409\u62c9\u6000\u7279\u5956&nbsp;<\/a><\/li><li><a href=\"#h-filmografia-de-angela-white\" data-level=\"2\">\u5b89\u5409\u62c9\u00b7\u6000\u7279\u7684\u5f71\u89c6\u4f5c\u54c1&nbsp;<\/a><\/li><\/ul><\/div>","protected":false},"featured_media":80200,"template":"","blog-categoria":[45],"class_list":["post-80195","blog","type-blog","status-publish","has-post-thumbnail","hentry","blog-categoria-pornostars"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Angela White - Conoce a la mejor actriz y directora de cine para adultos<\/title>\n<meta name=\"description\" content=\"Angela White es, sin duda, un referente de la industria cinematogr\u00e1fica para adultos. Conoce un poco m\u00e1s de su vida AQU\u00cd.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angela White - Conoce a la mejor actriz y directora de cine para adultos\" \/>\n<meta property=\"og:description\" content=\"Angela White es, sin duda, un referente de la industria cinematogr\u00e1fica para adultos. Conoce un poco m\u00e1s de su vida AQU\u00cd.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.argxp.com\/zh\/\u535a\u5ba2\/angela-white\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 \u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/\",\"url\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/\",\"name\":\"Angela White - Conoce a la mejor actriz y directora de cine para adultos\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2022-05-02T15:00:00+00:00\",\"description\":\"Angela White es, sin duda, un referente de la industria cinematogr\u00e1fica para adultos. Conoce un poco m\u00e1s de su vida AQU\u00cd.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/\"]}],\"accessibilityFeature\":[\"tableOfContents\"]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.argxp.com\\\/it\\\/blog\\\/angela-white\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/blog.argxp.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angela White\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/blog.argxp.com\\\/#website\",\"url\":\"http:\\\/\\\/blog.argxp.com\\\/\",\"name\":\"Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/blog.argxp.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5b89\u5409\u62c9\u6000\u7279 - \u8ba4\u8bc6\u6700\u4f73\u6210\u4eba\u7535\u5f71\u5973\u6f14\u5458\u548c\u5bfc\u6f14","description":"\u6beb\u65e0\u7591\u95ee\uff0c\u5b89\u5409\u62c9-\u6000\u7279\u662f\u6210\u4eba\u7535\u5f71\u754c\u7684\u5178\u8303\u3002\u70b9\u51fb\u8fd9\u91cc\u4e86\u89e3\u66f4\u591a\u5173\u4e8e\u5979\u7684\u751f\u6d3b\u3002","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"zh_CN","og_type":"article","og_title":"Angela White - Conoce a la mejor actriz y directora de cine para adultos","og_description":"Angela White es, sin duda, un referente de la industria cinematogr\u00e1fica para adultos. Conoce un poco m\u00e1s de su vida AQU\u00cd.","og_url":"https:\/\/blog.argxp.com\/zh\/\u535a\u5ba2\/angela-white\/","og_site_name":"Blog","twitter_card":"summary_large_image","twitter_misc":{"\u9884\u8ba1\u9605\u8bfb\u65f6\u95f4":"4 \u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.argxp.com\/it\/blog\/angela-white\/","url":"https:\/\/blog.argxp.com\/it\/blog\/angela-white\/","name":"\u5b89\u5409\u62c9\u6000\u7279 - \u8ba4\u8bc6\u6700\u4f73\u6210\u4eba\u7535\u5f71\u5973\u6f14\u5458\u548c\u5bfc\u6f14","isPartOf":{"@id":"http:\/\/blog.argxp.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/angela-white\/#primaryimage"},"image":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/angela-white\/#primaryimage"},"thumbnailUrl":"","datePublished":"2022-05-02T15:00:00+00:00","description":"\u6beb\u65e0\u7591\u95ee\uff0c\u5b89\u5409\u62c9-\u6000\u7279\u662f\u6210\u4eba\u7535\u5f71\u754c\u7684\u5178\u8303\u3002\u70b9\u51fb\u8fd9\u91cc\u4e86\u89e3\u66f4\u591a\u5173\u4e8e\u5979\u7684\u751f\u6d3b\u3002","breadcrumb":{"@id":"https:\/\/blog.argxp.com\/it\/blog\/angela-white\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.argxp.com\/it\/blog\/angela-white\/"]}],"accessibilityFeature":["tableOfContents"]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/blog.argxp.com\/it\/blog\/angela-white\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/blog.argxp.com\/it\/blog\/angela-white\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/blog.argxp.com\/"},{"@type":"ListItem","position":2,"name":"Angela White"}]},{"@type":"WebSite","@id":"http:\/\/blog.argxp.com\/#website","url":"http:\/\/blog.argxp.com\/","name":"\u535a\u5ba2","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/blog.argxp.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"}]}},"_links":{"self":[{"href":"https:\/\/blog.argxp.com\/zh\/wp-json\/wp\/v2\/blog\/80195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.argxp.com\/zh\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/blog.argxp.com\/zh\/wp-json\/wp\/v2\/types\/blog"}],"wp:attachment":[{"href":"https:\/\/blog.argxp.com\/zh\/wp-json\/wp\/v2\/media?parent=80195"}],"wp:term":[{"taxonomy":"blog-categoria","embeddable":true,"href":"https:\/\/blog.argxp.com\/zh\/wp-json\/wp\/v2\/blog-categoria?post=80195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}